{"id":9374,"date":"2025-06-14T16:24:28","date_gmt":"2025-06-14T14:24:28","guid":{"rendered":"https:\/\/mouillere.com\/AnneFredEditions\/?p=9374"},"modified":"2025-06-29T16:43:12","modified_gmt":"2025-06-29T14:43:12","slug":"morro-de-sao-paulo-a-boipeba","status":"publish","type":"post","link":"https:\/\/mouillere.com\/AnneFredEditions\/morro-de-sao-paulo-a-boipeba\/","title":{"rendered":"Morro de Sa\u0303o Paulo a Boipeba"},"content":{"rendered":"<p><iframe loading=\"lazy\"  id=\"_ytid_72297\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\" src=\"https:\/\/www.youtube.com\/embed\/OnIdy_D1iUo?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/p>\n<p><!--more--><\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"640\" data-carousel-extra='null' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 640px; height: 385px;\" data-original-width=\"640\" data-original-height=\"385\" > <div class=\"gallery-group images-1\" style=\"width: 385px; height: 385px;\" data-original-width=\"385\" data-original-height=\"385\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-1-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"381\"> <meta itemprop=\"height\" content=\"381\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9375\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-1-sur-105.jpeg\" data-orig-size=\"1280,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749826969&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 1 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-1-sur-105.jpeg?fit=600%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-1-sur-105.jpeg?fit=640%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-1-sur-105.jpeg?w=381&#038;h=381&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-1-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-1-sur-105.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-1-sur-105.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-1-sur-105.jpeg?resize=300%2C300&amp;ssl=1 300w\" width=\"381\" height=\"381\" loading=\"lazy\" data-original-width=\"381\" data-original-height=\"381\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 1 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 1 sur 105\" style=\"width: 381px; height: 381px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 255px; height: 385px;\" data-original-width=\"255\" data-original-height=\"385\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-2-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"251\"> <meta itemprop=\"height\" content=\"189\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9376\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-2-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749827382&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 2 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-2-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-2-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-2-sur-105.jpeg?w=251&#038;h=189&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-2-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-2-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-2-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-2-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"251\" height=\"189\" loading=\"lazy\" data-original-width=\"251\" data-original-height=\"189\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 2 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 2 sur 105\" style=\"width: 251px; height: 189px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-3-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"251\"> <meta itemprop=\"height\" content=\"188\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9377\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-3-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749836357&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0083333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 3 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-3-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-3-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-3-sur-105.jpeg?w=251&#038;h=188&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-3-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-3-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-3-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-3-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"251\" height=\"188\" loading=\"lazy\" data-original-width=\"251\" data-original-height=\"188\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 3 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 3 sur 105\" style=\"width: 251px; height: 188px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 161px;\" data-original-width=\"640\" data-original-height=\"161\" > <div class=\"gallery-group images-1\" style=\"width: 214px; height: 161px;\" data-original-width=\"214\" data-original-height=\"161\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-4-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"210\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9378\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-4-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749837142&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 4 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-4-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-4-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-4-sur-105.jpeg?w=210&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-4-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-4-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-4-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-4-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"210\" height=\"157\" loading=\"lazy\" data-original-width=\"210\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 4 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 4 sur 105\" style=\"width: 210px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 213px; height: 161px;\" data-original-width=\"213\" data-original-height=\"161\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-5-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9379\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-5-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749899694&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 5 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-5-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-5-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-5-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-5-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-5-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-5-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-5-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 5 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 5 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 213px; height: 161px;\" data-original-width=\"213\" data-original-height=\"161\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9380\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749899849&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 6 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 6 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 6 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 321px;\" data-original-width=\"640\" data-original-height=\"321\" > <div class=\"gallery-group images-2\" style=\"width: 213px; height: 321px;\" data-original-width=\"213\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-7-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9381\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-7-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749899905&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005998800239952&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 7 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-7-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-7-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-7-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-7-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-7-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-7-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-7-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 7 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 7 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-8-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"156\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9382\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-8-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749899947&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 8 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-8-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-8-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-8-sur-105.jpeg?w=209&#038;h=156&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-8-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-8-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-8-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-8-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"156\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"156\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 8 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 8 sur 105\" style=\"width: 209px; height: 156px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 427px; height: 321px;\" data-original-width=\"427\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-9-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"423\"> <meta itemprop=\"height\" content=\"317\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9383\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-9-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749900025&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0003&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 9 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-9-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-9-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-9-sur-105.jpeg?w=423&#038;h=317&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-9-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-9-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-9-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-9-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"423\" height=\"317\" loading=\"lazy\" data-original-width=\"423\" data-original-height=\"317\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 9 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 9 sur 105\" style=\"width: 423px; height: 317px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 241px;\" data-original-width=\"640\" data-original-height=\"241\" > <div class=\"gallery-group images-1\" style=\"width: 320px; height: 241px;\" data-original-width=\"320\" data-original-height=\"241\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-10-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"237\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9384\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-10-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749900220&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005998800239952&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 10 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-10-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-10-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-10-sur-105.jpeg?w=316&#038;h=237&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-10-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-10-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-10-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-10-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"316\" height=\"237\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"237\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 10 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 10 sur 105\" style=\"width: 316px; height: 237px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 320px; height: 241px;\" data-original-width=\"320\" data-original-height=\"241\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-11-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"237\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9385\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-11-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749893367&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 11 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-11-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-11-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-11-sur-105.jpeg?w=316&#038;h=237&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-11-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-11-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-11-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-11-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"316\" height=\"237\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"237\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 11 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 11 sur 105\" style=\"width: 316px; height: 237px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 322px;\" data-original-width=\"640\" data-original-height=\"322\" > <div class=\"gallery-group images-1\" style=\"width: 427px; height: 322px;\" data-original-width=\"427\" data-original-height=\"322\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-12-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"423\"> <meta itemprop=\"height\" content=\"318\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9386\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-12-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749897140&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00047619047619048&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 12 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-12-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-12-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-12-sur-105.jpeg?w=423&#038;h=318&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-12-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-12-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-12-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-12-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"423\" height=\"318\" loading=\"lazy\" data-original-width=\"423\" data-original-height=\"318\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 12 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 12 sur 105\" style=\"width: 423px; height: 318px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 213px; height: 322px;\" data-original-width=\"213\" data-original-height=\"322\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-13-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9387\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-13-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749897433&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 13 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-13-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-13-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-13-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-13-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-13-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-13-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-13-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 13 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 13 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-14-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9388\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-14-sur-105.jpeg\" data-orig-size=\"1280,964\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749897705&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;46&quot;,&quot;shutter_speed&quot;:&quot;0.000265&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 14 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-14-sur-105.jpeg?fit=600%2C452&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-14-sur-105.jpeg?fit=640%2C482&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-14-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-14-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-14-sur-105.jpeg?resize=600%2C452&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-14-sur-105.jpeg?resize=1024%2C771&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-14-sur-105.jpeg?resize=300%2C226&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 14 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 14 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 413px;\" data-original-width=\"640\" data-original-height=\"413\" > <div class=\"gallery-group images-3\" style=\"width: 164px; height: 413px;\" data-original-width=\"164\" data-original-height=\"413\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-15-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"160\"> <meta itemprop=\"height\" content=\"121\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9389\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-15-sur-105.jpeg\" data-orig-size=\"1280,964\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749898016&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;46&quot;,&quot;shutter_speed&quot;:&quot;0.000292&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 15 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-15-sur-105.jpeg?fit=600%2C452&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-15-sur-105.jpeg?fit=640%2C482&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-15-sur-105.jpeg?w=160&#038;h=121&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-15-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-15-sur-105.jpeg?resize=600%2C452&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-15-sur-105.jpeg?resize=1024%2C771&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-15-sur-105.jpeg?resize=300%2C226&amp;ssl=1 300w\" width=\"160\" height=\"121\" loading=\"lazy\" data-original-width=\"160\" data-original-height=\"121\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 15 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 15 sur 105\" style=\"width: 160px; height: 121px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-16-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"160\"> <meta itemprop=\"height\" content=\"120\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9390\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-16-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749898495&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 16 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-16-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-16-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-16-sur-105.jpeg?w=160&#038;h=120&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-16-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-16-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-16-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-16-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"160\" height=\"120\" loading=\"lazy\" data-original-width=\"160\" data-original-height=\"120\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 16 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 16 sur 105\" style=\"width: 160px; height: 120px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-17-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"160\"> <meta itemprop=\"height\" content=\"160\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9391\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-17-sur-105.jpeg\" data-orig-size=\"1280,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749898817&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0021739130434783&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 17 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-17-sur-105.jpeg?fit=600%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-17-sur-105.jpeg?fit=640%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-17-sur-105.jpeg?w=160&#038;h=160&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-17-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-17-sur-105.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-17-sur-105.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-17-sur-105.jpeg?resize=300%2C300&amp;ssl=1 300w\" width=\"160\" height=\"160\" loading=\"lazy\" data-original-width=\"160\" data-original-height=\"160\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 17 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 17 sur 105\" style=\"width: 160px; height: 160px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 311px; height: 413px;\" data-original-width=\"311\" data-original-height=\"413\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-18-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"307\"> <meta itemprop=\"height\" content=\"409\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9392\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-18-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749898926&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0038461538461538&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 18 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-18-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-18-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-18-sur-105.jpeg?w=307&#038;h=409&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-18-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-18-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-18-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-18-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"307\" height=\"409\" loading=\"lazy\" data-original-width=\"307\" data-original-height=\"409\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 18 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 18 sur 105\" style=\"width: 307px; height: 409px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-3\" style=\"width: 165px; height: 413px;\" data-original-width=\"165\" data-original-height=\"413\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-19-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"161\"> <meta itemprop=\"height\" content=\"120\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9393\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-19-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749899354&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00035714285714286&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 19 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-19-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-19-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-19-sur-105.jpeg?w=161&#038;h=120&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-19-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-19-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-19-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-19-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"161\" height=\"120\" loading=\"lazy\" data-original-width=\"161\" data-original-height=\"120\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 19 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 19 sur 105\" style=\"width: 161px; height: 120px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-20-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"161\"> <meta itemprop=\"height\" content=\"161\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9394\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-20-sur-105.jpeg\" data-orig-size=\"1280,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749908172&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0071428571428571&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 20 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-20-sur-105.jpeg?fit=600%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-20-sur-105.jpeg?fit=640%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-20-sur-105.jpeg?w=161&#038;h=161&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-20-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-20-sur-105.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-20-sur-105.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-20-sur-105.jpeg?resize=300%2C300&amp;ssl=1 300w\" width=\"161\" height=\"161\" loading=\"lazy\" data-original-width=\"161\" data-original-height=\"161\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 20 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 20 sur 105\" style=\"width: 161px; height: 161px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-21-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"161\"> <meta itemprop=\"height\" content=\"120\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9395\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-21-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749908839&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0018867924528302&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 21 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-21-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-21-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-21-sur-105.jpeg?w=161&#038;h=120&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-21-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-21-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-21-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-21-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"161\" height=\"120\" loading=\"lazy\" data-original-width=\"161\" data-original-height=\"120\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 21 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 21 sur 105\" style=\"width: 161px; height: 120px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 226px;\" data-original-width=\"640\" data-original-height=\"226\" > <div class=\"gallery-group images-1\" style=\"width: 170px; height: 226px;\" data-original-width=\"170\" data-original-height=\"226\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-22-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"166\"> <meta itemprop=\"height\" content=\"222\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9396\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-22-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749912284&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 22 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-22-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-22-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-22-sur-105.jpeg?w=166&#038;h=222&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-22-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-22-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-22-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-22-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"166\" height=\"222\" loading=\"lazy\" data-original-width=\"166\" data-original-height=\"222\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 22 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 22 sur 105\" style=\"width: 166px; height: 222px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 300px; height: 226px;\" data-original-width=\"300\" data-original-height=\"226\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-23-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"296\"> <meta itemprop=\"height\" content=\"222\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9397\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-23-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749916643&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0083333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 23 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-23-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-23-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-23-sur-105.jpeg?w=296&#038;h=222&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-23-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-23-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-23-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-23-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"296\" height=\"222\" loading=\"lazy\" data-original-width=\"296\" data-original-height=\"222\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 23 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 23 sur 105\" style=\"width: 296px; height: 222px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 170px; height: 226px;\" data-original-width=\"170\" data-original-height=\"226\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-24-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"166\"> <meta itemprop=\"height\" content=\"222\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9398\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-24-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749917494&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0083333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 24 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-24-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-24-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-24-sur-105.jpeg?w=166&#038;h=222&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-24-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-24-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-24-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-24-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"166\" height=\"222\" loading=\"lazy\" data-original-width=\"166\" data-original-height=\"222\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 24 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 24 sur 105\" style=\"width: 166px; height: 222px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 425px;\" data-original-width=\"640\" data-original-height=\"425\" > <div class=\"gallery-group images-1\" style=\"width: 320px; height: 425px;\" data-original-width=\"320\" data-original-height=\"425\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-25-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"421\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9399\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-25-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749918235&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 25 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-25-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-25-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-25-sur-105.jpeg?w=316&#038;h=421&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-25-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-25-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-25-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-25-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"316\" height=\"421\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"421\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 25 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 25 sur 105\" style=\"width: 316px; height: 421px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 320px; height: 425px;\" data-original-width=\"320\" data-original-height=\"425\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-26-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"421\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9400\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-26-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749918331&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 26 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-26-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-26-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-26-sur-105.jpeg?w=316&#038;h=421&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-26-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-26-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-26-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-26-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"316\" height=\"421\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"421\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 26 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 26 sur 105\" style=\"width: 316px; height: 421px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 321px;\" data-original-width=\"640\" data-original-height=\"321\" > <div class=\"gallery-group images-1\" style=\"width: 427px; height: 321px;\" data-original-width=\"427\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-27-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"423\"> <meta itemprop=\"height\" content=\"317\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9401\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-27-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749920417&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 27 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-27-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-27-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-27-sur-105.jpeg?w=423&#038;h=317&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-27-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-27-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-27-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-27-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"423\" height=\"317\" loading=\"lazy\" data-original-width=\"423\" data-original-height=\"317\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 27 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 27 sur 105\" style=\"width: 423px; height: 317px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 213px; height: 321px;\" data-original-width=\"213\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-28-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9402\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-28-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749989735&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0012&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 28 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-28-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-28-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-28-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-28-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-28-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-28-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-28-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 28 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 28 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-29-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"156\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9403\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-29-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749989814&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0012&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 29 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-29-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-29-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-29-sur-105.jpeg?w=209&#038;h=156&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-29-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-29-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-29-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-29-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"156\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"156\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 29 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 29 sur 105\" style=\"width: 209px; height: 156px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 321px;\" data-original-width=\"640\" data-original-height=\"321\" > <div class=\"gallery-group images-2\" style=\"width: 213px; height: 321px;\" data-original-width=\"213\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-30-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9404\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-30-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749989936&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 30 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-30-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-30-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-30-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-30-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-30-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-30-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-30-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 30 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 30 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-31-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"156\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9405\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-31-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749991845&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005998800239952&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 31 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-31-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-31-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-31-sur-105.jpeg?w=209&#038;h=156&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-31-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-31-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-31-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-31-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"156\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"156\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 31 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 31 sur 105\" style=\"width: 209px; height: 156px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 427px; height: 321px;\" data-original-width=\"427\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-32-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"423\"> <meta itemprop=\"height\" content=\"317\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9406\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-32-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749991880&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0014992503748126&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 32 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-32-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-32-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-32-sur-105.jpeg?w=423&#038;h=317&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-32-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-32-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-32-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-32-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"423\" height=\"317\" loading=\"lazy\" data-original-width=\"423\" data-original-height=\"317\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 32 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 32 sur 105\" style=\"width: 423px; height: 317px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 161px;\" data-original-width=\"640\" data-original-height=\"161\" > <div class=\"gallery-group images-1\" style=\"width: 214px; height: 161px;\" data-original-width=\"214\" data-original-height=\"161\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-33-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"210\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9407\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-33-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749991897&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0012&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 33 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-33-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-33-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-33-sur-105.jpeg?w=210&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-33-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-33-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-33-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-33-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"210\" height=\"157\" loading=\"lazy\" data-original-width=\"210\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 33 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 33 sur 105\" style=\"width: 210px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 213px; height: 161px;\" data-original-width=\"213\" data-original-height=\"161\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-34-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9408\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-34-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749991917&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0012&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 34 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-34-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-34-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-34-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-34-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-34-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-34-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-34-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 34 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 34 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 213px; height: 161px;\" data-original-width=\"213\" data-original-height=\"161\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-35-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9409\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-35-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749992014&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005998800239952&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 35 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-35-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-35-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-35-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-35-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-35-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-35-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-35-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 35 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 35 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 308px;\" data-original-width=\"640\" data-original-height=\"308\" > <div class=\"gallery-group images-2\" style=\"width: 204px; height: 308px;\" data-original-width=\"204\" data-original-height=\"308\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-36-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"200\"> <meta itemprop=\"height\" content=\"150\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9410\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-36-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749992089&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 36 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-36-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-36-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-36-sur-105.jpeg?w=200&#038;h=150&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-36-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-36-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-36-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-36-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"200\" height=\"150\" loading=\"lazy\" data-original-width=\"200\" data-original-height=\"150\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 36 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 36 sur 105\" style=\"width: 200px; height: 150px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-37-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"200\"> <meta itemprop=\"height\" content=\"150\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9411\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-37-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749985406&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0016949152542373&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 37 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-37-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-37-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-37-sur-105.jpeg?w=200&#038;h=150&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-37-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-37-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-37-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-37-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"200\" height=\"150\" loading=\"lazy\" data-original-width=\"200\" data-original-height=\"150\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 37 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 37 sur 105\" style=\"width: 200px; height: 150px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 232px; height: 308px;\" data-original-width=\"232\" data-original-height=\"308\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-38-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"228\"> <meta itemprop=\"height\" content=\"304\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9412\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-38-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749985813&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0037037037037037&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 38 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-38-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-38-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-38-sur-105.jpeg?w=228&#038;h=304&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-38-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-38-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-38-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-38-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"228\" height=\"304\" loading=\"lazy\" data-original-width=\"228\" data-original-height=\"304\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 38 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 38 sur 105\" style=\"width: 228px; height: 304px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 204px; height: 308px;\" data-original-width=\"204\" data-original-height=\"308\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-39-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"200\"> <meta itemprop=\"height\" content=\"150\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9413\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-39-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749987091&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00027777777777778&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 39 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-39-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-39-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-39-sur-105.jpeg?w=200&#038;h=150&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-39-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-39-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-39-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-39-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"200\" height=\"150\" loading=\"lazy\" data-original-width=\"200\" data-original-height=\"150\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 39 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 39 sur 105\" style=\"width: 200px; height: 150px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-40-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"200\"> <meta itemprop=\"height\" content=\"150\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9414\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-40-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749992668&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.98&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 40 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-40-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-40-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-40-sur-105.jpeg?w=200&#038;h=150&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-40-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-40-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-40-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-40-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"200\" height=\"150\" loading=\"lazy\" data-original-width=\"200\" data-original-height=\"150\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 40 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 40 sur 105\" style=\"width: 200px; height: 150px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 540px;\" data-original-width=\"640\" data-original-height=\"540\" > <div class=\"gallery-group images-1\" style=\"width: 408px; height: 540px;\" data-original-width=\"408\" data-original-height=\"540\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-41-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"404\"> <meta itemprop=\"height\" content=\"536\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9415\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-41-sur-105.jpeg\" data-orig-size=\"964,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749996500&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;43&quot;,&quot;shutter_speed&quot;:&quot;0.000221&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 41 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-41-sur-105.jpeg?fit=452%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-41-sur-105.jpeg?fit=640%2C850&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-41-sur-105.jpeg?w=404&#038;h=536&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-41-sur-105.jpeg?w=964&amp;ssl=1 964w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-41-sur-105.jpeg?resize=452%2C600&amp;ssl=1 452w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-41-sur-105.jpeg?resize=771%2C1024&amp;ssl=1 771w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-41-sur-105.jpeg?resize=226%2C300&amp;ssl=1 226w\" width=\"404\" height=\"536\" loading=\"lazy\" data-original-width=\"404\" data-original-height=\"536\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 41 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 41 sur 105\" style=\"width: 404px; height: 536px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-3\" style=\"width: 232px; height: 540px;\" data-original-width=\"232\" data-original-height=\"540\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-42-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"228\"> <meta itemprop=\"height\" content=\"171\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9416\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-42-sur-105.jpeg\" data-orig-size=\"1280,961\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1749997861&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 42 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-42-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-42-sur-105.jpeg?fit=640%2C481&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-42-sur-105.jpeg?w=228&#038;h=171&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-42-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-42-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-42-sur-105.jpeg?resize=1024%2C769&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-42-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"228\" height=\"171\" loading=\"lazy\" data-original-width=\"228\" data-original-height=\"171\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 42 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 42 sur 105\" style=\"width: 228px; height: 171px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-43-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"228\"> <meta itemprop=\"height\" content=\"228\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9417\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-43-sur-105.jpeg\" data-orig-size=\"1280,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750002835&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 43 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-43-sur-105.jpeg?fit=600%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-43-sur-105.jpeg?fit=640%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-43-sur-105.jpeg?w=228&#038;h=228&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-43-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-43-sur-105.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-43-sur-105.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-43-sur-105.jpeg?resize=300%2C300&amp;ssl=1 300w\" width=\"228\" height=\"228\" loading=\"lazy\" data-original-width=\"228\" data-original-height=\"228\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 43 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 43 sur 105\" style=\"width: 228px; height: 228px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-44-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"228\"> <meta itemprop=\"height\" content=\"129\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9418\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-44-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750003353&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0035714285714286&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 44 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-44-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-44-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-44-sur-105.jpeg?w=228&#038;h=129&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-44-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-44-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-44-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-44-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"228\" height=\"129\" loading=\"lazy\" data-original-width=\"228\" data-original-height=\"129\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 44 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 44 sur 105\" style=\"width: 228px; height: 129px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 337px;\" data-original-width=\"640\" data-original-height=\"337\" > <div class=\"gallery-group images-1\" style=\"width: 448px; height: 337px;\" data-original-width=\"448\" data-original-height=\"337\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-45-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"444\"> <meta itemprop=\"height\" content=\"333\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9419\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-45-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750005593&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0019230769230769&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 45 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-45-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-45-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-45-sur-105.jpeg?w=444&#038;h=333&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-45-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-45-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-45-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-45-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"444\" height=\"333\" loading=\"lazy\" data-original-width=\"444\" data-original-height=\"333\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 45 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 45 sur 105\" style=\"width: 444px; height: 333px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 192px; height: 337px;\" data-original-width=\"192\" data-original-height=\"337\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-46-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"188\"> <meta itemprop=\"height\" content=\"188\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9420\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-46-sur-105.jpeg\" data-orig-size=\"1280,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750005878&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 46 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-46-sur-105.jpeg?fit=600%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-46-sur-105.jpeg?fit=640%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-46-sur-105.jpeg?w=188&#038;h=188&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-46-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-46-sur-105.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-46-sur-105.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-46-sur-105.jpeg?resize=300%2C300&amp;ssl=1 300w\" width=\"188\" height=\"188\" loading=\"lazy\" data-original-width=\"188\" data-original-height=\"188\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 46 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 46 sur 105\" style=\"width: 188px; height: 188px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-47-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"188\"> <meta itemprop=\"height\" content=\"141\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9421\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-47-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750007296&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 47 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-47-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-47-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-47-sur-105.jpeg?w=188&#038;h=141&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-47-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-47-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-47-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-47-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"188\" height=\"141\" loading=\"lazy\" data-original-width=\"188\" data-original-height=\"141\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 47 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 47 sur 105\" style=\"width: 188px; height: 141px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 484px;\" data-original-width=\"640\" data-original-height=\"484\" > <div class=\"gallery-group images-2\" style=\"width: 276px; height: 484px;\" data-original-width=\"276\" data-original-height=\"484\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-48-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"272\"> <meta itemprop=\"height\" content=\"204\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9422\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-48-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750007587&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 48 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-48-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-48-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-48-sur-105.jpeg?w=272&#038;h=204&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-48-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-48-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-48-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-48-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"272\" height=\"204\" loading=\"lazy\" data-original-width=\"272\" data-original-height=\"204\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 48 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 48 sur 105\" style=\"width: 272px; height: 204px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-49-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"272\"> <meta itemprop=\"height\" content=\"272\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9423\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-49-sur-105.jpeg\" data-orig-size=\"1280,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750076890&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0038461538461538&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 49 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-49-sur-105.jpeg?fit=600%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-49-sur-105.jpeg?fit=640%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-49-sur-105.jpeg?w=272&#038;h=272&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-49-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-49-sur-105.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-49-sur-105.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-49-sur-105.jpeg?resize=300%2C300&amp;ssl=1 300w\" width=\"272\" height=\"272\" loading=\"lazy\" data-original-width=\"272\" data-original-height=\"272\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 49 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 49 sur 105\" style=\"width: 272px; height: 272px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 364px; height: 484px;\" data-original-width=\"364\" data-original-height=\"484\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-50-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"360\"> <meta itemprop=\"height\" content=\"480\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9424\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-50-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750078766&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0011363636363636&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 50 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-50-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-50-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-50-sur-105.jpeg?w=360&#038;h=480&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-50-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-50-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-50-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-50-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"360\" height=\"480\" loading=\"lazy\" data-original-width=\"360\" data-original-height=\"480\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 50 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 50 sur 105\" style=\"width: 360px; height: 480px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 207px;\" data-original-width=\"640\" data-original-height=\"207\" > <div class=\"gallery-group images-1\" style=\"width: 275px; height: 207px;\" data-original-width=\"275\" data-original-height=\"207\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-51-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"271\"> <meta itemprop=\"height\" content=\"203\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9425\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-51-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750078960&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 51 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-51-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-51-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-51-sur-105.jpeg?w=271&#038;h=203&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-51-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-51-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-51-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-51-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"271\" height=\"203\" loading=\"lazy\" data-original-width=\"271\" data-original-height=\"203\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 51 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 51 sur 105\" style=\"width: 271px; height: 203px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 365px; height: 207px;\" data-original-width=\"365\" data-original-height=\"207\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-52-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"361\"> <meta itemprop=\"height\" content=\"203\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9426\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-52-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750079338&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;71&quot;,&quot;shutter_speed&quot;:&quot;0.000751&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 52 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-52-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-52-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-52-sur-105.jpeg?w=361&#038;h=203&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-52-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-52-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-52-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-52-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"361\" height=\"203\" loading=\"lazy\" data-original-width=\"361\" data-original-height=\"203\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 52 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 52 sur 105\" style=\"width: 361px; height: 203px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 373px;\" data-original-width=\"640\" data-original-height=\"373\" > <div class=\"gallery-group images-3\" style=\"width: 145px; height: 373px;\" data-original-width=\"145\" data-original-height=\"373\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-53-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"141\"> <meta itemprop=\"height\" content=\"141\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9427\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-53-sur-105.jpeg\" data-orig-size=\"1280,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750079976&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;54&quot;,&quot;shutter_speed&quot;:&quot;0.000459&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 53 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-53-sur-105.jpeg?fit=600%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-53-sur-105.jpeg?fit=640%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-53-sur-105.jpeg?w=141&#038;h=141&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-53-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-53-sur-105.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-53-sur-105.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-53-sur-105.jpeg?resize=300%2C300&amp;ssl=1 300w\" width=\"141\" height=\"141\" loading=\"lazy\" data-original-width=\"141\" data-original-height=\"141\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 53 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 53 sur 105\" style=\"width: 141px; height: 141px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-54-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"141\"> <meta itemprop=\"height\" content=\"79\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9428\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-54-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750081075&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0032258064516129&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 54 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-54-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-54-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-54-sur-105.jpeg?w=141&#038;h=79&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-54-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-54-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-54-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-54-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"141\" height=\"79\" loading=\"lazy\" data-original-width=\"141\" data-original-height=\"79\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 54 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 54 sur 105\" style=\"width: 141px; height: 79px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-55-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"141\"> <meta itemprop=\"height\" content=\"141\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9429\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-55-sur-105.jpeg\" data-orig-size=\"1280,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750081437&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.000618&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 55 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-55-sur-105.jpeg?fit=600%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-55-sur-105.jpeg?fit=640%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-55-sur-105.jpeg?w=141&#038;h=141&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-55-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-55-sur-105.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-55-sur-105.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-55-sur-105.jpeg?resize=300%2C300&amp;ssl=1 300w\" width=\"141\" height=\"141\" loading=\"lazy\" data-original-width=\"141\" data-original-height=\"141\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 55 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 55 sur 105\" style=\"width: 141px; height: 141px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 299px; height: 373px;\" data-original-width=\"299\" data-original-height=\"373\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-56-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"295\"> <meta itemprop=\"height\" content=\"369\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9430\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-56-sur-105.jpeg\" data-orig-size=\"1024,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750081801&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0045454545454545&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 56 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-56-sur-105.jpeg?fit=480%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-56-sur-105.jpeg?fit=640%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-56-sur-105.jpeg?w=295&#038;h=369&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-56-sur-105.jpeg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-56-sur-105.jpeg?resize=480%2C600&amp;ssl=1 480w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-56-sur-105.jpeg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-56-sur-105.jpeg?resize=240%2C300&amp;ssl=1 240w\" width=\"295\" height=\"369\" loading=\"lazy\" data-original-width=\"295\" data-original-height=\"369\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 56 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 56 sur 105\" style=\"width: 295px; height: 369px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-3\" style=\"width: 196px; height: 373px;\" data-original-width=\"196\" data-original-height=\"373\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-57-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"192\"> <meta itemprop=\"height\" content=\"108\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9431\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-57-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750085118&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 57 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-57-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-57-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-57-sur-105.jpeg?w=192&#038;h=108&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-57-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-57-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-57-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-57-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"192\" height=\"108\" loading=\"lazy\" data-original-width=\"192\" data-original-height=\"108\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 57 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 57 sur 105\" style=\"width: 192px; height: 108px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-58-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"192\"> <meta itemprop=\"height\" content=\"108\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9432\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-58-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750085438&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;56&quot;,&quot;shutter_speed&quot;:&quot;0.000822&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 58 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-58-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-58-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-58-sur-105.jpeg?w=192&#038;h=108&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-58-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-58-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-58-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-58-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"192\" height=\"108\" loading=\"lazy\" data-original-width=\"192\" data-original-height=\"108\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 58 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 58 sur 105\" style=\"width: 192px; height: 108px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-59-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"192\"> <meta itemprop=\"height\" content=\"145\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9433\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-59-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750085517&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0083333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 59 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-59-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-59-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-59-sur-105.jpeg?w=192&#038;h=145&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-59-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-59-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-59-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-59-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"192\" height=\"145\" loading=\"lazy\" data-original-width=\"192\" data-original-height=\"145\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 59 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 59 sur 105\" style=\"width: 192px; height: 145px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 338px;\" data-original-width=\"640\" data-original-height=\"338\" > <div class=\"gallery-group images-1\" style=\"width: 447px; height: 338px;\" data-original-width=\"447\" data-original-height=\"338\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-60-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"443\"> <meta itemprop=\"height\" content=\"334\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9434\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-60-sur-105.jpeg\" data-orig-size=\"1280,964\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750085518&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;46&quot;,&quot;shutter_speed&quot;:&quot;0.000892&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 60 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-60-sur-105.jpeg?fit=600%2C452&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-60-sur-105.jpeg?fit=640%2C482&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-60-sur-105.jpeg?w=443&#038;h=334&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-60-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-60-sur-105.jpeg?resize=600%2C452&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-60-sur-105.jpeg?resize=1024%2C771&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-60-sur-105.jpeg?resize=300%2C226&amp;ssl=1 300w\" width=\"443\" height=\"334\" loading=\"lazy\" data-original-width=\"443\" data-original-height=\"334\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 60 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 60 sur 105\" style=\"width: 443px; height: 334px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 193px; height: 338px;\" data-original-width=\"193\" data-original-height=\"338\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-61-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"189\"> <meta itemprop=\"height\" content=\"141\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9435\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-61-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750085563&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.001219512195122&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 61 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-61-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-61-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-61-sur-105.jpeg?w=189&#038;h=141&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-61-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-61-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-61-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-61-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"189\" height=\"141\" loading=\"lazy\" data-original-width=\"189\" data-original-height=\"141\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 61 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 61 sur 105\" style=\"width: 189px; height: 141px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-62-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"189\"> <meta itemprop=\"height\" content=\"189\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9436\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-62-sur-105.jpeg\" data-orig-size=\"1280,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750085671&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;55&quot;,&quot;shutter_speed&quot;:&quot;0.000813&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 62 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-62-sur-105.jpeg?fit=600%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-62-sur-105.jpeg?fit=640%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-62-sur-105.jpeg?w=189&#038;h=189&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-62-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-62-sur-105.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-62-sur-105.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-62-sur-105.jpeg?resize=300%2C300&amp;ssl=1 300w\" width=\"189\" height=\"189\" loading=\"lazy\" data-original-width=\"189\" data-original-height=\"189\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 62 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 62 sur 105\" style=\"width: 189px; height: 189px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 263px;\" data-original-width=\"640\" data-original-height=\"263\" > <div class=\"gallery-group images-2\" style=\"width: 198px; height: 263px;\" data-original-width=\"198\" data-original-height=\"263\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-63-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"194\"> <meta itemprop=\"height\" content=\"109\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9437\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-63-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750085789&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;60&quot;,&quot;shutter_speed&quot;:&quot;0.000618&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 63 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-63-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-63-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-63-sur-105.jpeg?w=194&#038;h=109&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-63-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-63-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-63-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-63-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"194\" height=\"109\" loading=\"lazy\" data-original-width=\"194\" data-original-height=\"109\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 63 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 63 sur 105\" style=\"width: 194px; height: 109px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-64-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"194\"> <meta itemprop=\"height\" content=\"146\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9438\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-64-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750086080&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0011363636363636&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 64 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-64-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-64-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-64-sur-105.jpeg?w=194&#038;h=146&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-64-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-64-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-64-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-64-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"194\" height=\"146\" loading=\"lazy\" data-original-width=\"194\" data-original-height=\"146\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 64 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 64 sur 105\" style=\"width: 194px; height: 146px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 211px; height: 263px;\" data-original-width=\"211\" data-original-height=\"263\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-65-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"207\"> <meta itemprop=\"height\" content=\"259\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9439\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-65-sur-105.jpeg\" data-orig-size=\"1024,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750086104&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0022222222222222&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 65 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-65-sur-105.jpeg?fit=480%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-65-sur-105.jpeg?fit=640%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-65-sur-105.jpeg?w=207&#038;h=259&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-65-sur-105.jpeg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-65-sur-105.jpeg?resize=480%2C600&amp;ssl=1 480w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-65-sur-105.jpeg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-65-sur-105.jpeg?resize=240%2C300&amp;ssl=1 240w\" width=\"207\" height=\"259\" loading=\"lazy\" data-original-width=\"207\" data-original-height=\"259\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 65 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 65 sur 105\" style=\"width: 207px; height: 259px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 231px; height: 263px;\" data-original-width=\"231\" data-original-height=\"263\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-66-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"227\"> <meta itemprop=\"height\" content=\"128\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9440\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-66-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750086232&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00083333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 66 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-66-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-66-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-66-sur-105.jpeg?w=227&#038;h=128&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-66-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-66-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-66-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-66-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"227\" height=\"128\" loading=\"lazy\" data-original-width=\"227\" data-original-height=\"128\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 66 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 66 sur 105\" style=\"width: 227px; height: 128px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-67-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"227\"> <meta itemprop=\"height\" content=\"127\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9441\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-67-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750086255&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;47&quot;,&quot;shutter_speed&quot;:&quot;0.00061&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 67 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-67-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-67-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-67-sur-105.jpeg?w=227&#038;h=127&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-67-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-67-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-67-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-67-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"227\" height=\"127\" loading=\"lazy\" data-original-width=\"227\" data-original-height=\"127\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 67 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 67 sur 105\" style=\"width: 227px; height: 127px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 322px;\" data-original-width=\"640\" data-original-height=\"322\" > <div class=\"gallery-group images-2\" style=\"width: 213px; height: 322px;\" data-original-width=\"213\" data-original-height=\"322\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-68-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9442\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-68-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750087952&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 68 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-68-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-68-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-68-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-68-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-68-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-68-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-68-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 68 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 68 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-69-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9443\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-69-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750087962&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 69 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-69-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-69-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-69-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-69-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-69-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-69-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-69-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 69 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 69 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 427px; height: 322px;\" data-original-width=\"427\" data-original-height=\"322\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-70-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"423\"> <meta itemprop=\"height\" content=\"318\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9444\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-70-sur-105.jpeg\" data-orig-size=\"1280,964\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750092074&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;45&quot;,&quot;shutter_speed&quot;:&quot;0.0047619999955558&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 70 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-70-sur-105.jpeg?fit=600%2C452&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-70-sur-105.jpeg?fit=640%2C482&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-70-sur-105.jpeg?w=423&#038;h=318&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-70-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-70-sur-105.jpeg?resize=600%2C452&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-70-sur-105.jpeg?resize=1024%2C771&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-70-sur-105.jpeg?resize=300%2C226&amp;ssl=1 300w\" width=\"423\" height=\"318\" loading=\"lazy\" data-original-width=\"423\" data-original-height=\"318\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 70 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 70 sur 105\" style=\"width: 423px; height: 318px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 188px;\" data-original-width=\"640\" data-original-height=\"188\" > <div class=\"gallery-group images-1\" style=\"width: 249px; height: 188px;\" data-original-width=\"249\" data-original-height=\"188\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-71-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"245\"> <meta itemprop=\"height\" content=\"184\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9445\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-71-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750092822&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 71 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-71-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-71-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-71-sur-105.jpeg?w=245&#038;h=184&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-71-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-71-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-71-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-71-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"245\" height=\"184\" loading=\"lazy\" data-original-width=\"245\" data-original-height=\"184\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 71 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 71 sur 105\" style=\"width: 245px; height: 184px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 142px; height: 188px;\" data-original-width=\"142\" data-original-height=\"188\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-72-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"138\"> <meta itemprop=\"height\" content=\"184\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9446\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-72-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750094337&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 72 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-72-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-72-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-72-sur-105.jpeg?w=138&#038;h=184&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-72-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-72-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-72-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-72-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"138\" height=\"184\" loading=\"lazy\" data-original-width=\"138\" data-original-height=\"184\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 72 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 72 sur 105\" style=\"width: 138px; height: 184px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 249px; height: 188px;\" data-original-width=\"249\" data-original-height=\"188\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-73-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"245\"> <meta itemprop=\"height\" content=\"184\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9447\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-73-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750161702&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0012&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 73 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-73-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-73-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-73-sur-105.jpeg?w=245&#038;h=184&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-73-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-73-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-73-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-73-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"245\" height=\"184\" loading=\"lazy\" data-original-width=\"245\" data-original-height=\"184\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 73 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 73 sur 105\" style=\"width: 245px; height: 184px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 321px;\" data-original-width=\"640\" data-original-height=\"321\" > <div class=\"gallery-group images-1\" style=\"width: 427px; height: 321px;\" data-original-width=\"427\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-74-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"423\"> <meta itemprop=\"height\" content=\"317\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9448\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-74-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750161779&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 74 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-74-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-74-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-74-sur-105.jpeg?w=423&#038;h=317&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-74-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-74-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-74-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-74-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"423\" height=\"317\" loading=\"lazy\" data-original-width=\"423\" data-original-height=\"317\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 74 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 74 sur 105\" style=\"width: 423px; height: 317px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 213px; height: 321px;\" data-original-width=\"213\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-75-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9449\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-75-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750161998&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 75 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-75-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-75-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-75-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-75-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-75-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-75-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-75-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 75 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 75 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-76-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"156\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9450\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-76-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750162029&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 76 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-76-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-76-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-76-sur-105.jpeg?w=209&#038;h=156&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-76-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-76-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-76-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-76-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"156\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"156\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 76 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 76 sur 105\" style=\"width: 209px; height: 156px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 241px;\" data-original-width=\"640\" data-original-height=\"241\" > <div class=\"gallery-group images-1\" style=\"width: 320px; height: 241px;\" data-original-width=\"320\" data-original-height=\"241\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-77-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"237\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9451\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-77-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750164559&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005998800239952&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 77 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-77-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-77-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-77-sur-105.jpeg?w=316&#038;h=237&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-77-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-77-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-77-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-77-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"316\" height=\"237\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"237\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 77 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 77 sur 105\" style=\"width: 316px; height: 237px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 320px; height: 241px;\" data-original-width=\"320\" data-original-height=\"241\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-78-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"237\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9452\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-78-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750164628&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 78 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-78-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-78-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-78-sur-105.jpeg?w=316&#038;h=237&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-78-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-78-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-78-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-78-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"316\" height=\"237\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"237\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 78 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 78 sur 105\" style=\"width: 316px; height: 237px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 321px;\" data-original-width=\"640\" data-original-height=\"321\" > <div class=\"gallery-group images-2\" style=\"width: 213px; height: 321px;\" data-original-width=\"213\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-79-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9453\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-79-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750164700&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005998800239952&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 79 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-79-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-79-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-79-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-79-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-79-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-79-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-79-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 79 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 79 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-80-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"156\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9454\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-80-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FC7303&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750164759&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.49&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 80 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-80-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-80-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-80-sur-105.jpeg?w=209&#038;h=156&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-80-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-80-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-80-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-80-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"156\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"156\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 80 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 80 sur 105\" style=\"width: 209px; height: 156px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 427px; height: 321px;\" data-original-width=\"427\" data-original-height=\"321\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-81-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"423\"> <meta itemprop=\"height\" content=\"317\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9455\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-81-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750150100&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.001123595505618&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 81 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-81-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-81-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-81-sur-105.jpeg?w=423&#038;h=317&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-81-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-81-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-81-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-81-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"423\" height=\"317\" loading=\"lazy\" data-original-width=\"423\" data-original-height=\"317\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 81 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 81 sur 105\" style=\"width: 423px; height: 317px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 161px;\" data-original-width=\"640\" data-original-height=\"161\" > <div class=\"gallery-group images-1\" style=\"width: 214px; height: 161px;\" data-original-width=\"214\" data-original-height=\"161\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-82-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"210\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9456\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-82-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750151540&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0020833333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 82 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-82-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-82-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-82-sur-105.jpeg?w=210&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-82-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-82-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-82-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-82-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"210\" height=\"157\" loading=\"lazy\" data-original-width=\"210\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 82 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 82 sur 105\" style=\"width: 210px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 213px; height: 161px;\" data-original-width=\"213\" data-original-height=\"161\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-83-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9457\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-83-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750157815&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0014084507042254&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 83 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-83-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-83-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-83-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-83-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-83-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-83-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-83-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 83 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 83 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 213px; height: 161px;\" data-original-width=\"213\" data-original-height=\"161\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-84-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9458\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-84-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750158290&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 84 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-84-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-84-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-84-sur-105.jpeg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-84-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-84-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-84-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-84-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 84 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 84 sur 105\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 300px;\" data-original-width=\"640\" data-original-height=\"300\" > <div class=\"gallery-group images-1\" style=\"width: 399px; height: 300px;\" data-original-width=\"399\" data-original-height=\"300\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-85-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"395\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9459\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-85-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750159267&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00037037037037037&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 85 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-85-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-85-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-85-sur-105.jpeg?w=395&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-85-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-85-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-85-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-85-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"395\" height=\"296\" loading=\"lazy\" data-original-width=\"395\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 85 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 85 sur 105\" style=\"width: 395px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 241px; height: 300px;\" data-original-width=\"241\" data-original-height=\"300\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-86-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"237\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9460\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-86-sur-105.jpeg\" data-orig-size=\"1024,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750159352&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.001063829787234&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 86 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-86-sur-105.jpeg?fit=480%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-86-sur-105.jpeg?fit=640%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-86-sur-105.jpeg?w=237&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-86-sur-105.jpeg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-86-sur-105.jpeg?resize=480%2C600&amp;ssl=1 480w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-86-sur-105.jpeg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-86-sur-105.jpeg?resize=240%2C300&amp;ssl=1 240w\" width=\"237\" height=\"296\" loading=\"lazy\" data-original-width=\"237\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 86 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 86 sur 105\" style=\"width: 237px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 425px;\" data-original-width=\"640\" data-original-height=\"425\" > <div class=\"gallery-group images-1\" style=\"width: 320px; height: 425px;\" data-original-width=\"320\" data-original-height=\"425\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-87-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"421\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9461\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-87-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750159565&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0052631578947368&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 87 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-87-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-87-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-87-sur-105.jpeg?w=316&#038;h=421&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-87-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-87-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-87-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-87-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"316\" height=\"421\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"421\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 87 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 87 sur 105\" style=\"width: 316px; height: 421px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 320px; height: 425px;\" data-original-width=\"320\" data-original-height=\"425\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-88-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"421\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9462\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-88-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750161043&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0003448275862069&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 88 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-88-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-88-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-88-sur-105.jpeg?w=316&#038;h=421&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-88-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-88-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-88-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-88-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"316\" height=\"421\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"421\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 88 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 88 sur 105\" style=\"width: 316px; height: 421px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 535px;\" data-original-width=\"640\" data-original-height=\"535\" > <div class=\"gallery-group images-1\" style=\"width: 404px; height: 535px;\" data-original-width=\"404\" data-original-height=\"535\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-89-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"400\"> <meta itemprop=\"height\" content=\"531\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9463\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-89-sur-105.jpeg\" data-orig-size=\"964,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.85&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Pixel 7 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750161258&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.81&quot;,&quot;iso&quot;:&quot;47&quot;,&quot;shutter_speed&quot;:&quot;0.00038&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 89 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-89-sur-105.jpeg?fit=452%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-89-sur-105.jpeg?fit=640%2C850&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-89-sur-105.jpeg?w=400&#038;h=531&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-89-sur-105.jpeg?w=964&amp;ssl=1 964w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-89-sur-105.jpeg?resize=452%2C600&amp;ssl=1 452w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-89-sur-105.jpeg?resize=771%2C1024&amp;ssl=1 771w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-89-sur-105.jpeg?resize=226%2C300&amp;ssl=1 226w\" width=\"400\" height=\"531\" loading=\"lazy\" data-original-width=\"400\" data-original-height=\"531\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 89 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 89 sur 105\" style=\"width: 400px; height: 531px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-3\" style=\"width: 236px; height: 535px;\" data-original-width=\"236\" data-original-height=\"535\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-90-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"232\"> <meta itemprop=\"height\" content=\"175\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9464\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-90-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750162295&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0023255813953488&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 90 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-90-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-90-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-90-sur-105.jpeg?w=232&#038;h=175&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-90-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-90-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-90-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-90-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"232\" height=\"175\" loading=\"lazy\" data-original-width=\"232\" data-original-height=\"175\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 90 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 90 sur 105\" style=\"width: 232px; height: 175px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-91-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"232\"> <meta itemprop=\"height\" content=\"174\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9465\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-91-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750163963&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.82&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 91 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-91-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-91-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-91-sur-105.jpeg?w=232&#038;h=174&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-91-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-91-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-91-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-91-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"232\" height=\"174\" loading=\"lazy\" data-original-width=\"232\" data-original-height=\"174\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 91 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 91 sur 105\" style=\"width: 232px; height: 174px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-92-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"232\"> <meta itemprop=\"height\" content=\"174\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9466\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-92-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750165329&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0024390243902439&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 92 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-92-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-92-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-92-sur-105.jpeg?w=232&#038;h=174&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-92-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-92-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-92-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-92-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"232\" height=\"174\" loading=\"lazy\" data-original-width=\"232\" data-original-height=\"174\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 92 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 92 sur 105\" style=\"width: 232px; height: 174px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 437px;\" data-original-width=\"640\" data-original-height=\"437\" > <div class=\"gallery-group images-2\" style=\"width: 290px; height: 437px;\" data-original-width=\"290\" data-original-height=\"437\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-93-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"286\"> <meta itemprop=\"height\" content=\"215\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9467\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-93-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750165428&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0018518518518519&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 93 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-93-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-93-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-93-sur-105.jpeg?w=286&#038;h=215&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-93-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-93-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-93-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-93-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"286\" height=\"215\" loading=\"lazy\" data-original-width=\"286\" data-original-height=\"215\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 93 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 93 sur 105\" style=\"width: 286px; height: 215px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-94-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"286\"> <meta itemprop=\"height\" content=\"214\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9468\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-94-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750165437&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00014705882352941&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 94 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-94-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-94-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-94-sur-105.jpeg?w=286&#038;h=214&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-94-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-94-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-94-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-94-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"286\" height=\"214\" loading=\"lazy\" data-original-width=\"286\" data-original-height=\"214\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 94 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 94 sur 105\" style=\"width: 286px; height: 214px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 350px; height: 437px;\" data-original-width=\"350\" data-original-height=\"437\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-95-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"346\"> <meta itemprop=\"height\" content=\"433\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9469\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-95-sur-105.jpeg\" data-orig-size=\"1024,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750172467&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.014492753623188&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 95 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-95-sur-105.jpeg?fit=480%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-95-sur-105.jpeg?fit=640%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-95-sur-105.jpeg?w=346&#038;h=433&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-95-sur-105.jpeg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-95-sur-105.jpeg?resize=480%2C600&amp;ssl=1 480w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-95-sur-105.jpeg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-95-sur-105.jpeg?resize=240%2C300&amp;ssl=1 240w\" width=\"346\" height=\"433\" loading=\"lazy\" data-original-width=\"346\" data-original-height=\"433\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 95 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 95 sur 105\" style=\"width: 346px; height: 433px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 452px;\" data-original-width=\"640\" data-original-height=\"452\" > <div class=\"gallery-group images-1\" style=\"width: 340px; height: 452px;\" data-original-width=\"340\" data-original-height=\"452\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-96-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"336\"> <meta itemprop=\"height\" content=\"448\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9470\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-96-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750172483&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 96 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-96-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-96-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-96-sur-105.jpeg?w=336&#038;h=448&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-96-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-96-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-96-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-96-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"336\" height=\"448\" loading=\"lazy\" data-original-width=\"336\" data-original-height=\"448\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 96 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 96 sur 105\" style=\"width: 336px; height: 448px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 300px; height: 452px;\" data-original-width=\"300\" data-original-height=\"452\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-97-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"296\"> <meta itemprop=\"height\" content=\"222\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9471\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-97-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750235357&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00066666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 97 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-97-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-97-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-97-sur-105.jpeg?w=296&#038;h=222&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-97-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-97-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-97-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-97-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"296\" height=\"222\" loading=\"lazy\" data-original-width=\"296\" data-original-height=\"222\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 97 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 97 sur 105\" style=\"width: 296px; height: 222px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-98-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"296\"> <meta itemprop=\"height\" content=\"222\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9472\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-98-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750236145&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.000625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 98 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-98-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-98-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-98-sur-105.jpeg?w=296&#038;h=222&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-98-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-98-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-98-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-98-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"296\" height=\"222\" loading=\"lazy\" data-original-width=\"296\" data-original-height=\"222\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 98 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 98 sur 105\" style=\"width: 296px; height: 222px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 132px;\" data-original-width=\"640\" data-original-height=\"132\" > <div class=\"gallery-group images-1\" style=\"width: 233px; height: 132px;\" data-original-width=\"233\" data-original-height=\"132\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-99-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"229\"> <meta itemprop=\"height\" content=\"128\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9473\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-99-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750236607&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.000625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 99 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-99-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-99-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-99-sur-105.jpeg?w=229&#038;h=128&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-99-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-99-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-99-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-99-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"229\" height=\"128\" loading=\"lazy\" data-original-width=\"229\" data-original-height=\"128\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 99 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 99 sur 105\" style=\"width: 229px; height: 128px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 175px; height: 132px;\" data-original-width=\"175\" data-original-height=\"132\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-100-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"171\"> <meta itemprop=\"height\" content=\"128\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9474\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-100-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750237283&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0022222222222222&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 100 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-100-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-100-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-100-sur-105.jpeg?w=171&#038;h=128&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-100-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-100-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-100-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-100-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"171\" height=\"128\" loading=\"lazy\" data-original-width=\"171\" data-original-height=\"128\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 100 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 100 sur 105\" style=\"width: 171px; height: 128px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 232px; height: 132px;\" data-original-width=\"232\" data-original-height=\"132\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-101-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"228\"> <meta itemprop=\"height\" content=\"128\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9475\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-101-sur-105.jpeg\" data-orig-size=\"1280,720\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750237557&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 101 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-101-sur-105.jpeg?fit=600%2C338&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-101-sur-105.jpeg?fit=640%2C360&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-101-sur-105.jpeg?w=228&#038;h=128&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-101-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-101-sur-105.jpeg?resize=600%2C338&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-101-sur-105.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-101-sur-105.jpeg?resize=300%2C169&amp;ssl=1 300w\" width=\"228\" height=\"128\" loading=\"lazy\" data-original-width=\"228\" data-original-height=\"128\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 101 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 101 sur 105\" style=\"width: 228px; height: 128px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 640px; height: 536px;\" data-original-width=\"640\" data-original-height=\"536\" > <div class=\"gallery-group images-3\" style=\"width: 237px; height: 536px;\" data-original-width=\"237\" data-original-height=\"536\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-102-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"175\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9476\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-102-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750242818&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 102 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-102-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-102-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-102-sur-105.jpeg?w=233&#038;h=175&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-102-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-102-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-102-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-102-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"233\" height=\"175\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"175\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 102 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 102 sur 105\" style=\"width: 233px; height: 175px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-103-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"175\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9477\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-103-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750245360&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 103 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-103-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-103-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-103-sur-105.jpeg?w=233&#038;h=175&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-103-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-103-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-103-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-103-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"233\" height=\"175\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"175\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 103 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 103 sur 105\" style=\"width: 233px; height: 175px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-104-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"174\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9478\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-104-sur-105.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750245894&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.83&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.00038461538461538&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 104 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-104-sur-105.jpeg?fit=600%2C450&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-104-sur-105.jpeg?fit=640%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-104-sur-105.jpeg?w=233&#038;h=174&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-104-sur-105.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-104-sur-105.jpeg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-104-sur-105.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-104-sur-105.jpeg?resize=300%2C225&amp;ssl=1 300w\" width=\"233\" height=\"174\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"174\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 104 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 104 sur 105\" style=\"width: 233px; height: 174px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 403px; height: 536px;\" data-original-width=\"403\" data-original-height=\"536\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-105-sur-105.jpeg?ssl=1\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"399\"> <meta itemprop=\"height\" content=\"532\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"9479\" data-orig-file=\"https:\/\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-105-sur-105.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;BVL-N49&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1750248880&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15.38&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0027777777777778&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Morro de Sa\u0303o Paulo a Boipeba &amp;#8211; 105 sur 105\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-105-sur-105.jpeg?fit=450%2C600&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-105-sur-105.jpeg?fit=640%2C853&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-105-sur-105.jpeg?w=399&#038;h=532&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-105-sur-105.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-105-sur-105.jpeg?resize=450%2C600&amp;ssl=1 450w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-105-sur-105.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-105-sur-105.jpeg?resize=225%2C300&amp;ssl=1 225w\" width=\"399\" height=\"532\" loading=\"lazy\" data-original-width=\"399\" data-original-height=\"532\" itemprop=\"http:\/\/schema.org\/image\" title=\"Morro de Sa\u0303o Paulo a Boipeba - 105 sur 105\" alt=\"Morro de Sa\u0303o Paulo a Boipeba - 105 sur 105\" style=\"width: 399px; height: 532px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":9380,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[487],"tags":[],"class_list":["post-9374","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-morro-de-sao-paulo-a-boipeba","post_format-post-format-video"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2025\/06\/Morro-de-Sao-Paulo-a-Boipeba-6-sur-105.jpeg?fit=1280%2C960&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p5YNem-2rc","jetpack-related-posts":[{"id":540,"url":"https:\/\/mouillere.com\/AnneFredEditions\/de-bangkok-a-siem-reap\/","url_meta":{"origin":9374,"position":0},"title":"De Bangkok \u00e0 Siem Reap","author":"Fr\u00e9d\u00e9ric Mouill\u00e8re","date":"11 mai 2016","format":"gallery","excerpt":"Avant de vous faire partager notre aventure, nous souhaitions remercier parents, amis et coll\u00e8gues qui apr\u00e8s avoir support\u00e9 notre pr\u00e9sence doivent endurer notre absence. Un grand Big Up en particulier \u00e0 Marie-Th\u00e9r\u00e8se et Michel qui s\u00b4occupent de\u00a0Cachou, \u00e0 Christine et Jean qui doivent prendre des cours d'informatique ..., \u00e0 Rico\u2026","rel":"","context":"Dans &quot;Bangkok&quot;","block_context":{"text":"Bangkok","link":"https:\/\/mouillere.com\/AnneFredEditions\/category\/thailande\/bangkok\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02505.ARW_.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02505.ARW_.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02505.ARW_.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02505.ARW_.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02505.ARW_.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":808,"url":"https:\/\/mouillere.com\/AnneFredEditions\/de-siem-reap-a-hua-hin\/","url_meta":{"origin":9374,"position":1},"title":"De Siem Reap \u00e0 Hua Hin","author":"Fr\u00e9d\u00e9ric Mouill\u00e8re","date":"23 mai 2016","format":false,"excerpt":"Une folle journ\u00e9e de trajet entre le Cambodge et la Tha\u00eflande\u00a0: 4h30 : r\u00e9veil pour prendre le bus \u00e0 5h30. 5h30 - 7h : pas de bus !!! 7h : une voiture vient miraculeusement nous prendre et nous am\u00e8ne \u00e0 la fronti\u00e8re de Poipet. 10h - 11h\u00a0: suite \u00e0 de\u2026","rel":"","context":"Dans &quot;Hua Hin&quot;","block_context":{"text":"Hua Hin","link":"https:\/\/mouillere.com\/AnneFredEditions\/category\/thailande\/hua-hin\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC03465.ARW_-1.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC03465.ARW_-1.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC03465.ARW_-1.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC03465.ARW_-1.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC03465.ARW_-1.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":571,"url":"https:\/\/mouillere.com\/AnneFredEditions\/nos-premiers-temples-a-angkor-et-le-groupe-de-roluos\/","url_meta":{"origin":9374,"position":2},"title":"Nos premiers temples \u00e0 Angkor et le groupe de Roluos","author":"Fr\u00e9d\u00e9ric Mouill\u00e8re","date":"15 mai 2016","format":"video","excerpt":"https:\/\/youtu.be\/HBrWIZkN1pI Les temples ne se limitent \u00e0 ceux d'Angkor\u00a0!!! C'est la raison pour laquelle nous avons d\u00e9cid\u00e9 de rester \u00e0 Siem Reap pour notre premier s\u00e9jour au Cambodge. Et nous devrons m\u00eame y revenir tant il y a de choses \u00e0 voir. Nous aurions pu commencer par les plus anciens\u2026","rel":"","context":"Dans &quot;Angkor&quot;","block_context":{"text":"Angkor","link":"https:\/\/mouillere.com\/AnneFredEditions\/category\/cambodge\/angkor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02588.ARW_.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02588.ARW_.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02588.ARW_.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02588.ARW_.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/05\/DSC02588.ARW_.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3884,"url":"https:\/\/mouillere.com\/AnneFredEditions\/bonne-arrivee-au-benin\/","url_meta":{"origin":9374,"position":3},"title":"Bonne arriv\u00e9e au B\u00e9nin","author":"Fr\u00e9d\u00e9ric Mouill\u00e8re","date":"20 avril 2017","format":"video","excerpt":"https:\/\/youtu.be\/WndVzCD-2jo D\u00e8s notre descente de l'avion, nous sommes accueillis par Khalid, le neveu de Zack, qui nous installe dans ce qui sera notre chez nous pour quelques semaines, un bel appartement moderne dans le quartier de Haie Vive \u00e0 Cotonou, la capitale \u00e9conomique du B\u00e9nin. C'est une ville dynamique, bruyante\u2026","rel":"","context":"Dans &quot;B\u00e9nin&quot;","block_context":{"text":"B\u00e9nin","link":"https:\/\/mouillere.com\/AnneFredEditions\/category\/benin\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2017\/04\/20170315_141343-EFFECTS.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2017\/04\/20170315_141343-EFFECTS.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2017\/04\/20170315_141343-EFFECTS.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2017\/04\/20170315_141343-EFFECTS.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2017\/04\/20170315_141343-EFFECTS.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3105,"url":"https:\/\/mouillere.com\/AnneFredEditions\/en-colombie-dans-les-pas-de-mateo\/","url_meta":{"origin":9374,"position":4},"title":"En Colombie, dans les pas de Mateo","author":"Fr\u00e9d\u00e9ric Mouill\u00e8re","date":"27 novembre 2016","format":"video","excerpt":"https:\/\/youtu.be\/bPbZj2qCZKg Nous passons nos premiers jours en Colombie, \u00e0 Bogota, chez Ana la fianc\u00e9e de L\u00e9o, qui nous accueille chaleureusement dans son appartement de Chapinero, quartier pris\u00e9 des artistes, de la jeunesse boh\u00e8me et des \u00e9tudiants. L\u00e9o, po\u00e8te et professeur de philosophie \u00e0 l\u2019universit\u00e9 d\u2019Amazonie \u00e9tait un ami tr\u00e8s proche\u2026","rel":"","context":"Dans &quot;Bogota&quot;","block_context":{"text":"Bogota","link":"https:\/\/mouillere.com\/AnneFredEditions\/category\/colombie\/bogota\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/11\/IMG_20161108_200257.jpg?fit=1200%2C827&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/11\/IMG_20161108_200257.jpg?fit=1200%2C827&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/11\/IMG_20161108_200257.jpg?fit=1200%2C827&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/11\/IMG_20161108_200257.jpg?fit=1200%2C827&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/11\/IMG_20161108_200257.jpg?fit=1200%2C827&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1789,"url":"https:\/\/mouillere.com\/AnneFredEditions\/__trashed\/","url_meta":{"origin":9374,"position":5},"title":"De Perth \u00e0 Exmouth sur les traces des Big Five marins","author":"Fr\u00e9d\u00e9ric Mouill\u00e8re","date":"1 septembre 2016","format":"video","excerpt":"https:\/\/youtu.be\/awvu8jHdK2o Notre visite de Western Australia a commenc\u00e9 en famille, chez Maimbo et Colin, qui nous ont accueilli dans leur maison de Victoria Park, pr\u00e8s de Perth. Le froid et\u00a0la pluie nous ont surpris d\u00e8s notre sortie de l'a\u00e9roport, mais la chaleur de leur accueil nous a fait oublier que\u2026","rel":"","context":"Dans &quot;Australie&quot;","block_context":{"text":"Australie","link":"https:\/\/mouillere.com\/AnneFredEditions\/category\/australie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/08\/DSC06987.ARW_.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/08\/DSC06987.ARW_.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/08\/DSC06987.ARW_.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/08\/DSC06987.ARW_.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/AnneFredEditions\/wp-content\/uploads\/2016\/08\/DSC06987.ARW_.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":false,"_links":{"self":[{"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/posts\/9374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/comments?post=9374"}],"version-history":[{"count":1,"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/posts\/9374\/revisions"}],"predecessor-version":[{"id":9480,"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/posts\/9374\/revisions\/9480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/media\/9380"}],"wp:attachment":[{"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/media?parent=9374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/categories?post=9374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mouillere.com\/AnneFredEditions\/wp-json\/wp\/v2\/tags?post=9374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}