{"id":6213,"date":"2024-09-09T22:03:45","date_gmt":"2024-09-09T21:03:45","guid":{"rendered":"https:\/\/mouillere.com\/universconvergents\/?p=6213"},"modified":"2024-09-10T19:25:16","modified_gmt":"2024-09-10T18:25:16","slug":"kourou-sans-dpo-sanctionnee-par-la-cnil","status":"publish","type":"post","link":"https:\/\/mouillere.com\/universconvergents\/2024\/09\/09\/kourou-sans-dpo-sanctionnee-par-la-cnil\/","title":{"rendered":"Kourou sans DPO sanctionn\u00e9e par la CNIL"},"content":{"rendered":"<p>Kourou, port de l&#8217;espace europ\u00e9en aux finances d\u00e9j\u00e0 fragiles, a \u00e9t\u00e9 sanctionn\u00e9e par la Cnil pour ne s\u2019\u00eatre toujours pas conform\u00e9e \u00e0 son obligation de d\u00e9signer un D\u00e9l\u00e9gu\u00e9 \u00e0 la Protection des Donn\u00e9es (DPO).<\/p>\n<p><!--more--><\/p>\n<p>La commune de Kourou, en tant qu\u2019autorit\u00e9 publique, a pour obligation de d\u00e9signer un d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (article 37 du RGPD). En raison de la persistance de ses manquements (absence de d\u00e9signation de DPO et d\u00e9faut de r\u00e9ponse \u00e0 la CNIL), une proc\u00e9dure de sanction a \u00e9t\u00e9 engag\u00e9e. Le 22 juillet 2024, la CNIL a d\u00e9cid\u00e9 de liquider l\u2019astreinte prononc\u00e9e \u00e0 l\u2019encontre de la commune de Kourou qui devra payer\u00a0 6 900\u20ac pour ne s\u2019\u00eatre toujours pas conform\u00e9e \u00e0 son obligation de d\u00e9signer un DPO malgr\u00e9 l\u2019injonction de la CNIL de d\u00e9cembre 2023 et la sanction de 5 000\u20ac assortie d\u2019une astreinte de 150\u20ac par jour de retard. Cette liquidation d\u2019astreinte partielle ne vient pas cl\u00f4turer la proc\u00e9dure, l\u2019injonction assortie de son astreinte court toujours tant que la commune de Kourou n\u2019a pas d\u00e9sign\u00e9 de d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es. Une nouvelle liquidation d\u2019astreinte pourra donc \u00eatre prononc\u00e9e.<\/p>\n<iframe src=\"\/\/docs.google.com\/viewer?url=https%3A%2F%2Fmouillere.com%2Funiversconvergents%2Fwp-content%2Fuploads%2F2024%2F09%2Fprocedures_sanctions_kourou.pdf&hl=fr&embedded=true\" class=\"gde-frame\" style=\"width:100%; height:500px; border: none;\" scrolling=\"no\"><\/iframe>\n<p class=\"gde-text\"><a href=\"https:\/\/mouillere.com\/universconvergents\/wp-content\/uploads\/2024\/09\/procedures_sanctions_kourou.pdf\" class=\"gde-link\">T\u00e9l\u00e9charger (PDF, 133KB)<\/a><\/p>\n<iframe src=\"\/\/docs.google.com\/viewer?url=https%3A%2F%2Fmouillere.com%2Funiversconvergents%2Fwp-content%2Fuploads%2F2024%2F09%2F2023-12-12-CNIL-KOUROU.pdf&hl=fr&embedded=true\" class=\"gde-frame\" style=\"width:100%; height:500px; border: none;\" scrolling=\"no\"><\/iframe>\n<p class=\"gde-text\"><a href=\"https:\/\/mouillere.com\/universconvergents\/wp-content\/uploads\/2024\/09\/2023-12-12-CNIL-KOUROU.pdf\" class=\"gde-link\">T\u00e9l\u00e9charger (PDF, 155KB)<\/a><\/p>\n<p><a href=\"https:\/\/www.cnil.fr\/fr\/sanction-non-designation-dun-dpo-commune-kourou\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cnil.fr\/fr\/sanction-non-designation-dun-dpo-commune-kourou<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kourou, port de l&#8217;espace europ\u00e9en aux finances d\u00e9j\u00e0 fragiles, a \u00e9t\u00e9 sanctionn\u00e9e par la Cnil pour ne s\u2019\u00eatre toujours pas conform\u00e9e \u00e0 son obligation de d\u00e9signer un D\u00e9l\u00e9gu\u00e9 \u00e0 la&hellip; <\/p>\n","protected":false},"author":1,"featured_media":6221,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,74],"tags":[],"class_list":["post-6213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-donnees-personnelles","category-it"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2024\/09\/procedures_sanctions_kourou-scaled.jpg?fit=2560%2C1005&ssl=1","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/p6jw1p-1Cd","jetpack-related-posts":[{"id":2529,"url":"https:\/\/mouillere.com\/universconvergents\/2017\/06\/10\/data-privacy-officer-dpo\/","url_meta":{"origin":6213,"position":0},"title":"Data Privacy Officer (DPO)","author":"Fred","date":"10 juin 2017","format":false,"excerpt":"L\u2019article 37 du r\u00e8glement europ\u00e9en 2016\/679 du 27 avril 2016 (RGDP) contraint certains responsables de traitement de d\u00e9signer un D\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (DPO) aupr\u00e8s des autorit\u00e9s de contr\u00f4le (la CNIL en France).\u00a0Les responsables de traitement et les sous-traitants devront d\u00e9signer un DPO s\u2019ils appartiennent au secteur public,\u2026","rel":"","context":"Dans &quot;Donn\u00e9es personnelles&quot;","block_context":{"text":"Donn\u00e9es personnelles","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/donnees-personnelles\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/06\/role-of-the-data-protection-officer-18-638.jpg?fit=638%2C479&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/06\/role-of-the-data-protection-officer-18-638.jpg?fit=638%2C479&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/06\/role-of-the-data-protection-officer-18-638.jpg?fit=638%2C479&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":2388,"url":"https:\/\/mouillere.com\/universconvergents\/2017\/05\/18\/le-nouveau-data-protection-officer-dpo\/","url_meta":{"origin":6213,"position":1},"title":"Le nouveau Data Protection Officer (DPO)","author":"Fred","date":"18 mai 2017","format":false,"excerpt":"Le\u00a0R\u00e8glement du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l\u2019\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es (\u00ab RGDP \u00bb) a cr\u00e9\u00e9 le DPO charg\u00e9\u00a0d'assurer un r\u00f4le d\u2019interm\u00e9diaire entre\u00a0les\u00a0entreprises et la CNIL. Le DPO va devenir obligatoire d'ici\u2026","rel":"","context":"Dans &quot;Donn\u00e9es personnelles&quot;","block_context":{"text":"Donn\u00e9es personnelles","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/donnees-personnelles\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/GDPR-en.png?fit=1101%2C560&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/GDPR-en.png?fit=1101%2C560&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/GDPR-en.png?fit=1101%2C560&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/GDPR-en.png?fit=1101%2C560&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/GDPR-en.png?fit=1101%2C560&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5152,"url":"https:\/\/mouillere.com\/universconvergents\/2022\/06\/29\/mooc-de-la-cnil-dedie-aux-aux-collectivites-territoriales\/","url_meta":{"origin":6213,"position":2},"title":"MOOC de la CNIL d\u00e9di\u00e9 aux aux collectivit\u00e9s territoriales","author":"Fred","date":"29 juin 2022","format":false,"excerpt":"L\u2019atelier RGPD est une formation en ligne gratuite, illimit\u00e9e et ouverte \u00e0 tous (Mooc). Elle permet de sensibiliser les professionnels \u00e0 la protection des donn\u00e9es et d\u2019accompagner leur mise en conformit\u00e9. Dans sa nouvelle version, la CNIL propose un nouveau module d\u00e9di\u00e9 aux collectivit\u00e9s territoriales Pour les collectivit\u00e9s territoriales qui\u2026","rel":"","context":"Dans &quot;Donn\u00e9es personnelles&quot;","block_context":{"text":"Donn\u00e9es personnelles","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/donnees-personnelles\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2015\/06\/6640564215_b3dc3f033d.jpg?fit=450%2C287&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5049,"url":"https:\/\/mouillere.com\/universconvergents\/2022\/04\/10\/guide-pratique-du-dpo\/","url_meta":{"origin":6213,"position":3},"title":"Guide pratique du DPO","author":"Fred","date":"10 avril 2022","format":false,"excerpt":"La CNIL vient de publier son guide pratique du DPO. Ce guide du DPO aborde les points suivants : R\u00f4le D\u00e9signation Exercice Accompagnement par la CNIL","rel":"","context":"Dans &quot;Donn\u00e9es personnelles&quot;","block_context":{"text":"Donn\u00e9es personnelles","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/donnees-personnelles\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2015\/06\/6640564215_b3dc3f033d.jpg?fit=450%2C287&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2806,"url":"https:\/\/mouillere.com\/universconvergents\/2018\/09\/25\/bilan-des-4-mois-de-rgpd-en-france\/","url_meta":{"origin":6213,"position":4},"title":"Bilan des 4 mois de RGPD en France","author":"Fred","date":"25 septembre 2018","format":false,"excerpt":"La CNIL vient de publier son bilan apr\u00e8s 4 mois de RGPD en France. Parmi ces chiffres, nous pouvons souligner que: 24 500 organismes ont d\u00e9sign\u00e9 un DPO ce qui repr\u00e9sente 13 000 DPO contre 5 000 CIL (correspondants informatique et libert\u00e9s) avant le RGPD ; \u00a0 Plus de 600\u2026","rel":"","context":"Dans &quot;Donn\u00e9es personnelles&quot;","block_context":{"text":"Donn\u00e9es personnelles","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/donnees-personnelles\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2018\/09\/visuel_actu_11.jpg?fit=975%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2018\/09\/visuel_actu_11.jpg?fit=975%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2018\/09\/visuel_actu_11.jpg?fit=975%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2018\/09\/visuel_actu_11.jpg?fit=975%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2958,"url":"https:\/\/mouillere.com\/universconvergents\/2019\/03\/12\/mooc-pour-le-rgpd\/","url_meta":{"origin":6213,"position":5},"title":"MOOC pour le RGPD","author":"Fred","date":"12 mars 2019","format":false,"excerpt":"La CNIL vient de mettre en ligne une formation en ligne gratuite \u00e0 destination des D\u00e9l\u00e9gu\u00e9s \u00e0 la Protection des donn\u00e9es comprenant : 1) Le RGPD et ses notions cl\u00e9s, 2) Les principes de la protection des donn\u00e9es, 3) Les responsabilit\u00e9s des acteurs, 4) Le DPO et les outils de\u2026","rel":"","context":"Dans &quot;Donn\u00e9es personnelles&quot;","block_context":{"text":"Donn\u00e9es personnelles","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/donnees-personnelles\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2015\/06\/6640564215_b3dc3f033d.jpg?fit=450%2C287&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts\/6213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/comments?post=6213"}],"version-history":[{"count":4,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts\/6213\/revisions"}],"predecessor-version":[{"id":6225,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts\/6213\/revisions\/6225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/media\/6221"}],"wp:attachment":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/media?parent=6213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/categories?post=6213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/tags?post=6213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}