{"id":6558,"date":"2025-04-16T22:02:03","date_gmt":"2025-04-16T21:02:03","guid":{"rendered":"https:\/\/mouillere.com\/universconvergents\/?p=6558"},"modified":"2025-04-17T19:53:43","modified_gmt":"2025-04-17T18:53:43","slug":"blockchain-rgpd","status":"publish","type":"post","link":"https:\/\/mouillere.com\/universconvergents\/2025\/04\/16\/blockchain-rgpd\/","title":{"rendered":"Blockchain &#038; RGPD"},"content":{"rendered":"<p>Compte tenu des difficult\u00e9s que peuvent poser les technologies blockchain en mati\u00e8re de protection des donn\u00e9es personnelles, notamment concernant le droit de rectification et de suppression des donn\u00e9es, le Comit\u00e9 europ\u00e9en de la protection des donn\u00e9es (CEPD) vient de publier une premi\u00e8re version de ses lignes directrices en \u00e9valuant les diff\u00e9rentes architectures possibles et leurs implications pour le traitement des donn\u00e9es personnelles. Ces lignes directrices sont soumises \u00e0 consultation publique jusqu\u2019au 9 juin 2025.<\/p>\n<p><!--more--><\/p>\n<p>La blockchain est un syst\u00e8me de base de donn\u00e9es distribu\u00e9e pouvant fonctionner sans gestion centralis\u00e9e. Une blockchain peut, par exemple, permettre des transactions financi\u00e8res sans interm\u00e9diaire financier tels que des banques en permettant de prouver la propri\u00e9t\u00e9 d\u2019un actif. La blockchain recouvre une grande vari\u00e9t\u00e9 de mod\u00e8les : publique ou priv\u00e9e, ouverte ou restreinte, avec des r\u00e8gles de participation et de gouvernance tr\u00e8s variables. Ces diff\u00e9rences ont un impact sur les op\u00e9rations de traitement susceptibles d\u2019\u00eatre mises en \u0153uvre et sur la capacit\u00e9 des responsables de traitements et sous-traitants d\u2019assurer la conformit\u00e9 aux r\u00e8gles du RGPD. Les donn\u00e9es personnelles susceptibles d&#8217;\u00eatre trait\u00e9es dans une blockchain sont \u00e9galement multiples : identifiants, adresses IP, donn\u00e9es biom\u00e9triques ou sensibles, etc. Les donn\u00e9es peuvent \u00eatre directement stock\u00e9es dans la blockchain ou \u00eatre simplement r\u00e9f\u00e9renc\u00e9es dans la cha\u00eene tout en \u00e9tant h\u00e9berg\u00e9es ailleurs.<\/p>\n<p>&nbsp;<\/p>\n<p>Le CEPD identifie plusieurs risques eu regard des exigences du RGPD, notamment :<\/p>\n<ul>\n<li><strong>Dur\u00e9e de conservation, droit de rectification et de suppression<\/strong>\u00a0: une fois enregistr\u00e9es, les donn\u00e9es inscrites dans la blockchain ne peuvent g\u00e9n\u00e9ralement plus \u00eatre supprim\u00e9es;<\/li>\n<li><strong>Minimisation des donn\u00e9es<\/strong> : l\u2019ajout successif et irr\u00e9versible de nouvelles donn\u00e9es sans possibilit\u00e9 de suppression;<\/li>\n<li><strong>Transferts de donn\u00e9es hors UE<\/strong>, notamment lorsque des n\u0153uds situ\u00e9s dans des pays tiers participent au r\u00e9seau;<\/li>\n<li><strong>Qualification du responsable de traitement<\/strong> : la d\u00e9centralisation rend complexe l\u2019identification du responsable de traitement, en particulier dans les blockchains dites \u00ab permissionless \u00bb. Les blockchains sans autorisation sont ouvertes \u00e0 tous (Bitcoin, Ethereum, etc.) tandis que les blockchains \u00e0 autorisation n\u00e9cessitent des invitations pour les rejoindre, le pouvoir \u00e9tant limit\u00e9 \u00e0 un petit groupe de validateurs qui prennent la plupart des d\u00e9cisions concernant le r\u00e9seau.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Or, l&#8217;absence de contr\u00f4le centralis\u00e9 ou l\u2019impossibilit\u00e9 d\u2019effacement ne peuvent exon\u00e9rer les acteurs de leurs obligations l\u00e9gales, notamment du respect du principe de privacy by design et by default (article 25 RGPD) :<\/p>\n<ul>\n<li><strong>N\u00e9cessit\u00e9 de recourir \u00e0 une blockchain :<\/strong> il convient d&#8217;analyser au moment de la conception si l\u2019utilisation d\u2019une blockchain est n\u00e9cessaire au regard des finalit\u00e9s poursuivies et si objectifs peuvent \u00eatre atteints via des technologies alternatives offrant de meilleures garanties en mati\u00e8re de protection des donn\u00e9es;<\/li>\n<li><strong>Choix du\u00a0type de blockchain<\/strong> adapt\u00e9 aux enjeux de protection des donn\u00e9es. Le CEPD recommande de privil\u00e9gier les blockchains \u00e0 autorisation permettant une meilleure gouvernance, r\u00e9partition des responsabilit\u00e9s, et offrant plus de garanties pour les droits des personnes concern\u00e9es;<\/li>\n<li><strong>Stockage de donn\u00e9es personnelles sur la cha\u00eene \u00e0 \u00e9viter :<\/strong> le stockage direct de donn\u00e9es personnelles sur la blockchain sans mesure de protection contrevient aux principes du RGPD. Le CEPD recommande de stocker les donn\u00e9es hors cha\u00eene (une simple r\u00e9f\u00e9rence non identifiante \u00e9tant stock\u00e9e sur la cha\u00eene) et d\u2019utiliser des techniques telles que le chiffrement, les fonctions de hachage, etc.<\/li>\n<li><strong>Limitation des donn\u00e9es trait\u00e9es et finalit\u00e9s poursuivies<\/strong>. Seules les donn\u00e9es strictement n\u00e9cessaires doivent \u00eatre trait\u00e9es. Le respect du principe de minimisation est essentiel car une fois les donn\u00e9es inscrites dans la blockchain, elles ne sont plus modifiables ni supprimables;<\/li>\n<li><strong>Cadre de gouvernance structur\u00e9 :<\/strong> les r\u00e8gles techniques, organisationnelles et juridiques doivent permettre d\u2019attribuer les r\u00f4les de responsable de traitement et de sous-traitant, de g\u00e9rer les acc\u00e8s, les incidents et les \u00e9volutions technologiques en mati\u00e8re de s\u00e9curit\u00e9 et de confidentialit\u00e9;<\/li>\n<li><strong>Exercice des droits des personnes :<\/strong>\u00a0Les projets blockchain doivent int\u00e9grer d\u00e8s leur conception des m\u00e9canismes permettant aux personnes d\u2019exercer leurs droits;<\/li>\n<li><strong>Analyse d\u2019impact<\/strong>\u00a0relative \u00e0 la protection des donn\u00e9es (AIPD).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<iframe src=\"\/\/docs.google.com\/viewer?url=https%3A%2F%2Fmouillere.com%2Funiversconvergents%2Fwp-content%2Fuploads%2F2025%2F04%2F2025-04-08-BlockchainRGPD.pdf&hl=fr&embedded=true\" class=\"gde-frame\" style=\"width:100%; height:500px; border: none;\" scrolling=\"no\"><\/iframe>\n<p class=\"gde-text\"><a href=\"https:\/\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/04\/2025-04-08-BlockchainRGPD.pdf\" class=\"gde-link\">T\u00e9l\u00e9charger (PDF, 541KB)<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.edpb.europa.eu\/our-work-tools\/documents\/public-consultations\/2025\/guidelines-022025-processing-personal-data_en\" target=\"_blank\" rel=\"noopener\">https:\/\/www.edpb.europa.eu\/our-work-tools\/documents\/public-consultations\/2025\/guidelines-022025-processing-personal-data_en<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.edpb.europa.eu\/news\/news\/2025\/edpb-adopts-guidelines-processing-personal-data-through-blockchains-and-ready_fr\" target=\"_blank\" rel=\"noopener\">https:\/\/www.edpb.europa.eu\/news\/news\/2025\/edpb-adopts-guidelines-processing-personal-data-through-blockchains-and-ready_fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compte tenu des difficult\u00e9s que peuvent poser les technologies blockchain en mati\u00e8re de protection des donn\u00e9es personnelles, notamment concernant le droit de rectification et de suppression des donn\u00e9es, le Comit\u00e9&hellip; <\/p>\n","protected":false},"author":1,"featured_media":6563,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[45,74],"tags":[],"class_list":["post-6558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain","category-it"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/04\/2025-04-08-BlockchainRGPD.jpg?fit=1024%2C768&ssl=1","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/p6jw1p-1HM","jetpack-related-posts":[{"id":2818,"url":"https:\/\/mouillere.com\/universconvergents\/2018\/09\/24\/blockchain-et-rgpd\/","url_meta":{"origin":6558,"position":0},"title":"Blockchain et RGPD","author":"Fred","date":"24 septembre 2018","format":false,"excerpt":"Le 24 septembre 2018, la CNIL a publi\u00e9 ses recommandations relatives \u00e0 la blockchain. Lorsque la Blockchain concerne des donn\u00e9es personnelles, le RGPD s\u2019applique. L\u2019architecture et les caract\u00e9ristiques propres des Blockchains vont toutefois avoir des cons\u00e9quences sur la mani\u00e8re dont sont conserv\u00e9es et trait\u00e9es les donn\u00e9es personnelles. La Blockchain peut\u2026","rel":"","context":"Dans &quot;Blockchain&quot;","block_context":{"text":"Blockchain","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/blockchain\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2018\/10\/GDPR-Blockchain-Shufti-Pro.png?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2018\/10\/GDPR-Blockchain-Shufti-Pro.png?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2018\/10\/GDPR-Blockchain-Shufti-Pro.png?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2018\/10\/GDPR-Blockchain-Shufti-Pro.png?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2667,"url":"https:\/\/mouillere.com\/universconvergents\/2017\/10\/10\/blockchain-et-environnement\/","url_meta":{"origin":6558,"position":1},"title":"Blockchain et environnement","author":"Fred","date":"10 octobre 2017","format":false,"excerpt":"La multiplication des offres en mati\u00e8re d'\u00e9nergie renouvelable par des fournisseurs comme ENGIE pose la question de la certification du caract\u00e8re renouvelable de l'\u00e9nergie.\u00a0Comment la blockchain permet-elle de certifier l'origine renouvelable de l'\u00e9nergie ? La blockchain pr\u00e9sente plusieurs fonctionnalit\u00e9s qui permettent de certifier l'origine renouvelable de l'\u00e9nergie : un registre\u2026","rel":"","context":"Dans &quot;Blockchain&quot;","block_context":{"text":"Blockchain","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/blockchain\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/10\/7-ways-blockchain-can-help-the-environment-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/10\/7-ways-blockchain-can-help-the-environment-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/10\/7-ways-blockchain-can-help-the-environment-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/10\/7-ways-blockchain-can-help-the-environment-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2351,"url":"https:\/\/mouillere.com\/universconvergents\/2017\/04\/26\/spotify-compte-sur-la-blockchain-pour-resoudre-les-problemes-didentification-des-droits-musicaux\/","url_meta":{"origin":6558,"position":2},"title":"Spotify compte sur la Blockchain pour r\u00e9soudre les probl\u00e8mes d&#8217;identification des droits musicaux","author":"Fred","date":"26 avril 2017","format":false,"excerpt":"Spotify vient d'acqu\u00e9rir Mediachain sp\u00e9cialis\u00e9e dans les technologies Blockchain pour une gestion d\u00e9centralis\u00e9e des droits musicaux. Ce rachat fait suite au\u00a0litige avec la NMPA\u00a0aux \u00c9tats-Unis relatifs \u00e0 des redevances impay\u00e9es pour un grand nombre d\u2019\u0153uvres diffus\u00e9es par Spotify. La plateforme de streaming\u00a0avait argu\u00e9 qu'elle n'avait pas payer les redevances parce\u2026","rel":"","context":"Dans &quot;Blockchain&quot;","block_context":{"text":"Blockchain","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/blockchain\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/C4PDKRaWcAAwlr3.jpg?fit=1200%2C654&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/C4PDKRaWcAAwlr3.jpg?fit=1200%2C654&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/C4PDKRaWcAAwlr3.jpg?fit=1200%2C654&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/C4PDKRaWcAAwlr3.jpg?fit=1200%2C654&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/C4PDKRaWcAAwlr3.jpg?fit=1200%2C654&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5059,"url":"https:\/\/mouillere.com\/universconvergents\/2022\/05\/09\/nft-blockchains-et-metavers-en-attendant-leclatement-de-la-bulle-internet-3-0\/","url_meta":{"origin":6558,"position":3},"title":"NFT, Blockchains et Metavers en attendant l&#8217;\u00e9clatement de la bulle internet 3.0","author":"Fred","date":"9 mai 2022","format":false,"excerpt":"Surm\u00e9diatis\u00e9es et survaloris\u00e9es, ces technologies dites d\u00e9centralis\u00e9es rappellent \u00a0les promesses du P2P et du march\u00e9 publicitaire des ann\u00e9es 90 avant l'\u00e9clatement de la bulle Internet en 2000. Promesses d'un monde virtuel meilleur ou d'un nouveau far west ? \u00a0 \"Il y a eu le e-commerce sur des sites web, le\u2026","rel":"","context":"Dans &quot;Blockchain&quot;","block_context":{"text":"Blockchain","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/blockchain\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2022\/05\/Capture-decran-2022-05-10-a-15.21.48.jpg?fit=1200%2C625&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2022\/05\/Capture-decran-2022-05-10-a-15.21.48.jpg?fit=1200%2C625&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2022\/05\/Capture-decran-2022-05-10-a-15.21.48.jpg?fit=1200%2C625&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2022\/05\/Capture-decran-2022-05-10-a-15.21.48.jpg?fit=1200%2C625&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2022\/05\/Capture-decran-2022-05-10-a-15.21.48.jpg?fit=1200%2C625&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2345,"url":"https:\/\/mouillere.com\/universconvergents\/2017\/05\/02\/la-blockchain-parmi-les-8-tech-trends-2017-de-deloitte\/","url_meta":{"origin":6558,"position":4},"title":"La Blockchain parmi les 8 &#8220;Tech Trends 2017&#8221; de Deloitte","author":"Fred","date":"2 mai 2017","format":false,"excerpt":"La Lettre de Petit Web consacre un article int\u00e9ressant illustr\u00e9 d'une infographie p\u00e9dagogique sur la Blockchain qui fait partie des 8 tendances technologiques de l'ann\u00e9e selon \"Tech Trends 2017\" de Deloitte. http:\/\/www.petitweb.fr\/actualites\/les-4-conseils-de-deloitte-avant-dexperimenter-avec-la-blockchain\/ https:\/\/dupress.deloitte.com\/dup-us-en\/focus\/tech-trends\/2017\/blockchain-trust-economy.html","rel":"","context":"Dans &quot;Blockchain&quot;","block_context":{"text":"Blockchain","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/blockchain\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2017\/05\/blockchain-deloitte.jpg?fit=232%2C1200&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1846,"url":"https:\/\/mouillere.com\/universconvergents\/2016\/02\/12\/et-si-la-blockchain-devait-devenir-la-base-de-nos-interactions\/","url_meta":{"origin":6558,"position":5},"title":"Et si la Blockchain devait devenir la base de nos interactions ?","author":"Fred","date":"12 f\u00e9vrier 2016","format":false,"excerpt":"\u00ab\u00a0Codeurs de tous les pays, unissez- vous\u00a0\u00bb, tel \u00e9tait, en substance, l\u2019injonction de Primavera de Filippi, en guise de conclusion de la conf\u00e9rence Blockchain du 14 janvier dernier. http:\/\/www.maddyness.com\/prospective\/2016\/02\/12\/blockchain-france\/","rel":"","context":"Dans &quot;Blockchain&quot;","block_context":{"text":"Blockchain","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/blockchain\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2016\/02\/blockchain-Axl-R.png?fit=715%2C476&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2016\/02\/blockchain-Axl-R.png?fit=715%2C476&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2016\/02\/blockchain-Axl-R.png?fit=715%2C476&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2016\/02\/blockchain-Axl-R.png?fit=715%2C476&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts\/6558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/comments?post=6558"}],"version-history":[{"count":4,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts\/6558\/revisions"}],"predecessor-version":[{"id":6564,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts\/6558\/revisions\/6564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/media\/6563"}],"wp:attachment":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/media?parent=6558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/categories?post=6558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/tags?post=6558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}