{"id":6820,"date":"2025-11-11T22:42:21","date_gmt":"2025-11-11T21:42:21","guid":{"rendered":"https:\/\/mouillere.com\/universconvergents\/?p=6820"},"modified":"2025-11-12T21:18:20","modified_gmt":"2025-11-12T20:18:20","slug":"openai-condamnee-pour-violation-des-droits-dauteur","status":"publish","type":"post","link":"https:\/\/mouillere.com\/universconvergents\/2025\/11\/11\/openai-condamnee-pour-violation-des-droits-dauteur\/","title":{"rendered":"OpenAI condamn\u00e9e pour violation des droits d\u2019auteur"},"content":{"rendered":"<p>Faisant suite \u00e0 la plainte de la GEMA (la SACEM allemande), le tribunal r\u00e9gional de Munich a condamn\u00e9 OpenAI (ChatGPT) mardi 11 novembre 2025 pour violation des droits d\u2019auteur via l&#8217;utilisation de paroles de chansons dans ses mod\u00e8les d\u2019IA sans autorisation ni r\u00e9mun\u00e9ration des auteurs.<\/p>\n<p><!--more--><\/p>\n<blockquote><p><em><strong>&#8220;L&#8217;internet n&#8217;est pas un magasin en libre-service et les r\u00e9alisations cr\u00e9atives humaines ne sont pas des mod\u00e8les gratuits (&#8230;) Aujourd&#8217;hui, nous avons cr\u00e9\u00e9 un pr\u00e9c\u00e9dent qui prot\u00e8ge et clarifie les droits des auteurs: m\u00eame les op\u00e9rateurs d&#8217;outils d&#8217;IA tels que ChatGPT doivent se conformer \u00e0 la l\u00e9gislation sur le droit d&#8217;auteur&#8221; Tobias Holzmueller, directeur g\u00e9n\u00e9ral de la GEMA<\/strong><\/em><\/p><\/blockquote>\n<p>OpenAI soutenait que ses mod\u00e8les ne stockent pas de donn\u00e9es individuelles, mais refl\u00e8tent des sch\u00e9mas appris \u00e0 partir d\u2019un vaste ensemble de donn\u00e9es. Le tribunal a estim\u00e9 que la m\u00e9morisation des paroles dans les mod\u00e8les et leur reproduction dans les r\u00e9ponses de ChatGPT constituent bien des violations, m\u00eame si elles sont indirectes. La cour s\u2019est appuy\u00e9e sur la jurisprudence de la Cour de justice de l\u2019Union europ\u00e9enne (CJUE), selon laquelle une reproduction indirecte de l\u2019\u0153uvre est suffisante pour caract\u00e9riser une reproduction illicite.<\/p>\n<p>En parall\u00e8le, la GEMA a lanc\u00e9 une proc\u00e9dure contre SunoAI, un autre acteur am\u00e9ricain proposant la g\u00e9n\u00e9ration de musique par IA. SunoAI utilise des enregistrements prot\u00e9g\u00e9s de chansons c\u00e9l\u00e8bres (melodie, harmonie, rythme) appartenant notamment au r\u00e9pertoire de la GEMA pour entra\u00eener son outil d\u2019IA, puis g\u00e9n\u00e8re des morceaux parfois tr\u00e8s similaires aux originaux. Des titres comme \u00ab Forever Young \u00bb (Alphaville), \u00ab Atemlos \u00bb (Helene Fischer), \u00ab Mambo No. 5 \u00bb, ou \u00ab Cheri Cheri Lady \u00bb ont \u00e9t\u00e9 reproduits de mani\u00e8re quasi identique par l\u2019IA de SunoAI, sans licence ni r\u00e9mun\u00e9ration des ayants droit. SunoAI n\u2019a pas divulgu\u00e9 les donn\u00e9es utilis\u00e9es pour entra\u00eener son IA, ce qui rend difficile la v\u00e9rification de l\u2019\u00e9tendue de l\u2019utilisation des \u0153uvres prot\u00e9g\u00e9es.<\/p>\n<p>Comme pour OpenAI, la GEMA ne cherche pas \u00e0 interdire la technologie mais \u00e0 imposer un mod\u00e8le de licence pour que les cr\u00e9ateurs soient r\u00e9mun\u00e9r\u00e9s lorsque leurs \u0153uvres sont utilis\u00e9es pour entra\u00eener ou g\u00e9n\u00e9rer de la musique par IA.<\/p>\n<p>La GEMA avait en effet propos\u00e9 d\u00e8s septembre 2024 un mod\u00e8le de licence sp\u00e9cifique pour les outils d\u2019IA, mais OpenAI avait refus\u00e9 de le souscrire. La GEMA esp\u00e8re que cette d\u00e9cision encouragera les entreprises d\u2019IA \u00e0 n\u00e9gocier des accords de licence pour une r\u00e9mun\u00e9ration \u00e9quitable des cr\u00e9ateurs.<\/p>\n<p><a href=\"https:\/\/www.zdnet.fr\/actualites\/openai-condamne-en-allemagne-pour-violation-de-droits-dauteur-un-tournant-historique-pour-lia-484761.htm\" target=\"_blank\" rel=\"noopener\">https:\/\/www.zdnet.fr\/actualites\/openai-condamne-en-allemagne-pour-violation-de-droits-dauteur-un-tournant-historique-pour-lia-484761.htm<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faisant suite \u00e0 la plainte de la GEMA (la SACEM allemande), le tribunal r\u00e9gional de Munich a condamn\u00e9 OpenAI (ChatGPT) mardi 11 novembre 2025 pour violation des droits d\u2019auteur via&hellip; <\/p>\n","protected":false},"author":1,"featured_media":6821,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[302,145,74,14],"tags":[],"class_list":["post-6820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ia","category-ip","category-it","category-propriete-litteraire-et-artistique"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/11\/GEMA-OpenAI.jpg?fit=1024%2C768&ssl=1","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/p6jw1p-1M0","jetpack-related-posts":[{"id":5737,"url":"https:\/\/mouillere.com\/universconvergents\/2023\/12\/28\/plainte-du-new-york-times-contre-chatgpt\/","url_meta":{"origin":6820,"position":0},"title":"Plainte du New York Times contre ChatGPT","author":"Fred","date":"28 d\u00e9cembre 2023","format":false,"excerpt":"Le New York Times poursuit en justice Open AI et Microsoft pour avoir utilis\u00e9 sans autorisation des articles de presse afin d'entrainer leurs robots d'intelligence artificielle g\u00e9n\u00e9rative. \u00a0 \"L\u2019IA g\u00e9n\u00e9rative des d\u00e9fendeurs repose sur des mod\u00e8les d\u2019apprentissage massif qui ont \u00e9t\u00e9 construits en copiant et utilisant des millions d\u2019articles du\u2026","rel":"","context":"Dans &quot;IA&quot;","block_context":{"text":"IA","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/ia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2023\/12\/NYTvsChatGPT.jpeg?fit=1024%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2023\/12\/NYTvsChatGPT.jpeg?fit=1024%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2023\/12\/NYTvsChatGPT.jpeg?fit=1024%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2023\/12\/NYTvsChatGPT.jpeg?fit=1024%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5830,"url":"https:\/\/mouillere.com\/universconvergents\/2024\/01\/14\/openai-impossible-de-faire-de-lia-sans-violer-les-droits-des-tiers\/","url_meta":{"origin":6820,"position":1},"title":"OpenAI : impossible de faire de l&#8217;IA sans violer les droits des tiers","author":"Fred","date":"14 janvier 2024","format":false,"excerpt":"Impossible de d\u00e9velopper Youtube sans violer les droits d'auteurs, Facebook et tweeter sans violer les donn\u00e9es personnel et v\u00e9hiculer massivement de la d\u00e9sinformation, Amazon sans violer le droit des marques, Uber sans violer le droit du travail, etc. Alors pourquoi toutes ces soci\u00e9t\u00e9s continuent \u00e0 s'autoriser \u00e0 distribuer des produits\u2026","rel":"","context":"Dans &quot;IA&quot;","block_context":{"text":"IA","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/ia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2024\/01\/IA.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2024\/01\/IA.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2024\/01\/IA.jpg?fit=1024%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2024\/01\/IA.jpg?fit=1024%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5650,"url":"https:\/\/mouillere.com\/universconvergents\/2023\/08\/22\/ia-les-oeuvres-creees-a-laide-de-lia-peuvent-elles-etre-protegees\/","url_meta":{"origin":6820,"position":2},"title":"IA : les oeuvres cr\u00e9\u00e9es \u00e0 l&#8217;aide de l&#8217;IA peuvent-elles \u00eatre prot\u00e9g\u00e9es ?","author":"Fred","date":"22 ao\u00fbt 2023","format":false,"excerpt":"La cr\u00e9ation assist\u00e9e par ordinateur n'est pas nouvelle. Demander \u00e0 David Guetta ! Tous les secteurs de la Propri\u00e9t\u00e9 Intellectuelle sont concern\u00e9s : oeuvres musicales, litt\u00e9raires, audiovisuelles, graphiques, picturales, architecturales, etc. La question de la propri\u00e9t\u00e9 et de la protection des droits de l'auteur des oeuvres cr\u00e9\u00e9es avec l'assistance informatique\u2026","rel":"","context":"Dans &quot;IA&quot;","block_context":{"text":"IA","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/ia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2023\/08\/Zarya-of-the-Dawn.jpg?fit=1200%2C530&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2023\/08\/Zarya-of-the-Dawn.jpg?fit=1200%2C530&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2023\/08\/Zarya-of-the-Dawn.jpg?fit=1200%2C530&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2023\/08\/Zarya-of-the-Dawn.jpg?fit=1200%2C530&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2023\/08\/Zarya-of-the-Dawn.jpg?fit=1200%2C530&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7053,"url":"https:\/\/mouillere.com\/universconvergents\/2026\/04\/01\/resolution-du-parlement-europeen-sur-le-droit-dauteur-et-lia\/","url_meta":{"origin":6820,"position":3},"title":"R\u00e9solution du Parlement Europ\u00e9en sur le Droit d&#8217;Auteur et l&#8217;IA","author":"Fred","date":"1 avril 2026","format":false,"excerpt":"Le 10 mars 2026, le Parlement europ\u00e9en a adopt\u00e9 la r\u00e9solution non contraignante port\u00e9e par l'eurod\u00e9put\u00e9 Axel Voss visant \u00e0 encadrer l'interaction entre le droit d'auteur et l'IA : Transparence : Obligation pour les fournisseurs d'IA de lister de mani\u00e8re d\u00e9taill\u00e9e les contenus prot\u00e9g\u00e9s utilis\u00e9s pour l'entra\u00eenement; Pr\u00e9somption r\u00e9fragable :\u2026","rel":"","context":"Dans &quot;IA&quot;","block_context":{"text":"IA","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/ia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2026\/04\/2026-03-10-EU-ResolutionIA.jpg?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2026\/04\/2026-03-10-EU-ResolutionIA.jpg?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2026\/04\/2026-03-10-EU-ResolutionIA.jpg?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2026\/04\/2026-03-10-EU-ResolutionIA.jpg?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6648,"url":"https:\/\/mouillere.com\/universconvergents\/2025\/07\/14\/ia-creation\/","url_meta":{"origin":6820,"position":4},"title":"IA &#038; Cr\u00e9ation","author":"Fred","date":"14 juillet 2025","format":false,"excerpt":"Le\u00a0S\u00e9nat\u00a0vient de publier son rapport sur l'IA et la Cr\u00e9ation\u00a0pour concilier innovation et cr\u00e9ation en garantissant l\u2019effectivit\u00e9 du droit d\u2019auteur et le partage de la valeur. Dans\u00a0le\u00a0domaine culturel, l\u2019IA\u00a0offre\u00a0de\u00a0nouvelles\u00a0opportunit\u00e9s\u00a0sur\u00a0le\u00a0plan\u00a0de\u00a0la\u00a0cr\u00e9ation\u00a0et\u00a0de\u00a0la\u00a0diffusion\u00a0des \u0153uvres, mais ses usages pr\u00e9sentent \u00e9galement des risques pour\u00a0le\u00a0statut\u00a0et\u00a0la\u00a0valeur\u00a0de\u00a0la\u00a0production\u00a0artistique,\u00a0ainsi\u00a0que\u00a0pour\u00a0les\u00a0droits\u00a0et\u00a0la\u00a0protection\u00a0des\u00a0auteurs. Les fournisseurs d'IA ont su exploiter les failles offertes par la r\u00e8glementation\u2026","rel":"","context":"Dans &quot;IA&quot;","block_context":{"text":"IA","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/ia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/07\/2025-07-09-IACreation-Synthese.png?fit=1200%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/07\/2025-07-09-IACreation-Synthese.png?fit=1200%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/07\/2025-07-09-IACreation-Synthese.png?fit=1200%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/07\/2025-07-09-IACreation-Synthese.png?fit=1200%2C768&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/07\/2025-07-09-IACreation-Synthese.png?fit=1200%2C768&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6428,"url":"https:\/\/mouillere.com\/universconvergents\/2025\/01\/06\/ia-un-transfert-de-valeur-bien-reel\/","url_meta":{"origin":6820,"position":5},"title":"IA : un transfert de valeur bien r\u00e9el","author":"Fred","date":"6 janvier 2025","format":false,"excerpt":"Plusieurs \u00e9tudes publi\u00e9es en fin d'ann\u00e9e permettent de comprendre l'impact de l'IA notamment dans le secteur culturel et le transfert des valeurs g\u00e9n\u00e9r\u00e9s, ce qui permet d'expliquer pourquoi certains g\u00e9ants du num\u00e9rique n'h\u00e9sitent pas \u00e0 se lancer en politique et orchestrent des campagne de d\u00e9sinformation dans l'UE pour \u00e0 terme\u2026","rel":"","context":"Dans &quot;IA&quot;","block_context":{"text":"IA","link":"https:\/\/mouillere.com\/universconvergents\/category\/it\/ia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/01\/2024-12-chaine-de-valeur-de-lIA.png?fit=1200%2C468&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/01\/2024-12-chaine-de-valeur-de-lIA.png?fit=1200%2C468&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/01\/2024-12-chaine-de-valeur-de-lIA.png?fit=1200%2C468&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/01\/2024-12-chaine-de-valeur-de-lIA.png?fit=1200%2C468&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mouillere.com\/universconvergents\/wp-content\/uploads\/2025\/01\/2024-12-chaine-de-valeur-de-lIA.png?fit=1200%2C468&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts\/6820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/comments?post=6820"}],"version-history":[{"count":3,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts\/6820\/revisions"}],"predecessor-version":[{"id":6824,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/posts\/6820\/revisions\/6824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/media\/6821"}],"wp:attachment":[{"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/media?parent=6820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/categories?post=6820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mouillere.com\/universconvergents\/wp-json\/wp\/v2\/tags?post=6820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}